{"id":21513,"date":"2019-02-01T12:30:34","date_gmt":"2019-02-01T12:30:34","guid":{"rendered":"https:\/\/www.bca.ad\/previa-joventut-todos-los-ingredientes-para-que-sea-un-partidazo\/"},"modified":"2019-02-01T12:38:34","modified_gmt":"2019-02-01T12:38:34","slug":"previa-joventut-todos-los-ingredientes-para-que-sea-un-partidazo","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-joventut-todos-los-ingredientes-para-que-sea-un-partidazo\/","title":{"rendered":"PREVIA JOVENTUT Todos los ingredientes para que sea un partidazo"},"content":{"rendered":"<p><strong>Partidazo ma\u00f1ana en la Bombonera. Por todo. El MoraBanc, que est\u00e1 en racha, recibe a las 20h30 el Divina Seguros Joventut de Badalona que est\u00e1 haciendo una temporada sensacional hasta ahora que la ha llevado a clasificarse para la Copa del Rey. Partidazo porque vendr\u00e1n muchos seguidores verdinegra y eso siempre dar color y m\u00e1s ambiente a los partidos. Y partidazo tambi\u00e9n porque entre el tercer y el \u00faltimo cuarto los espectadores enviar\u00e1n al mundo una ola de luz contra el c\u00e1ncer<\/strong>. Pero el carril central del inter\u00e9s es un enorme partido de baloncesto entre dos equipos que querr\u00e1n mantener las buenas din\u00e1micas en las que est\u00e1n. Por lo tanto, los espectadores se aproxima un regalo de los que hacen la boca agua s\u00f3lo de pensarlo.<\/p>\n<p>En esta etapa ACB, la Bombonera ha sido terreno vedado por la Pe\u00f1a que, a pesar de luchar esto siempre, no ha sido capaz de ganar aqu\u00ed. Y el objetivo de los de Ibon Navarro ser\u00e1 mantener as\u00ed las cosas. Y para ello saben que tendr\u00e1n que encontrar la manera de controlar lo mejor que puedan (anularlo por completo a d\u00eda de hoy parece imposible) el jugador m\u00e1s en forma de la liga, el argentino Nico Laprovittola, autor de 40 puntos el fin de semana pasado en una gran exhibici\u00f3n. El Joventut no es s\u00f3lo Laprovittola, aunque el juego gira en su entorno, sino un bloque que tiene las cosas claras y que tiene armas relevantes en todas las posiciones. El alero Shawn Dawson estar\u00e1 de baja 10 d\u00edas y ser\u00e1 una ausencia importante para los de Carlos duramente.<\/p>\n<p>El MoraBanc, por su parte, cuenta con el regreso de Jel\u00ednek y Albicy a la liga despu\u00e9s de haber reaparecido en Eurocup. La duda es c\u00f3mo estar\u00e1 Miki Vitali que el mi\u00e9rcoles fue v\u00edctima del virus estomacal que ha ido afectando a plantilla y cuerpo t\u00e9cnico. La otra duda es qui\u00e9n ser\u00e1 el siguiente o si ya se habr\u00e1 terminado el problema. Para los tricolores el partido es importante para que consolidar a buena l\u00ednea como locales despu\u00e9s de un inicio de liga con muchas dudas jugando como local.<\/p>\n<p><strong>Hoy ha comparecido en rueda de prensa David Jel\u00ednek que ha expuesto que &#8220;tenemos que estar mejor<\/strong> <strong>que el pasado mi\u00e9rcoles contra Cedevita porque ellos llegan en un gran momento. Tendremos que estar concentrados en Laprovittola no s\u00f3lo por su capacidad anotadora<\/strong>, tambi\u00e9n por lo que genera por sus compa\u00f1eros&#8221;. Sobre el rival, el escolta ha dicho que &#8220;debemos ser capaces de parar su contraataque, el tiro de tres puntos y la capacidad para generar de Laprovittola, estos son los retos que tenemos para ma\u00f1ana&#8221;. Preguntado sobre su rodilla, el jugador checo afirm\u00f3 que &#8220;todav\u00eda noto cansada la rodilla pero cada d\u00eda estoy mejor&#8221;.<\/p>\n<p><strong>En la rueda de prensa Ibon Navarro n<\/strong>o ha ocultado la admiraci\u00f3n por el juego del rival &#8220;se destaca mucho el trabajo que hace en ataque el Joventut pero detr\u00e1s tambi\u00e9n est\u00e1n haciendo muy bien las cosas. Est\u00e1n jugando muy bien y llegan en muy buena din\u00e1mica de resultados. Para nosotros ganar el Joventut tal y como est\u00e1n haciendo las cosas es un reto &#8220;. Y no dribl\u00f3 el tema Laprovittola &#8220;tienen un jugador que est\u00e1 por encima no de sus compa\u00f1eros sino de la mayor\u00eda de jugadores de la liga que es Laprovittola. <strong>A pesar de que puedas hacer una buena defensa acaba aportando muchos puntos pero tampoco nos podemos centrar s\u00f3lo en frenarlo porque es capaz de pasar muy bien el bal\u00f3n y sus compa\u00f1eros han demostrado que tienen mucha calidad &#8220;.<\/strong><\/p>\n<p><strong>Ma\u00f1ana celebramos el partido Caldea.<\/strong><\/p>\n<p>* El Termol\u00fadico celebra este a\u00f1o su 25 aniversario.<\/p>\n<p>* Al descanso haremos un concurso de slalom donde participar\u00e1n padres \/ madres y sus hijos \/ hijas. El premio estar\u00e1n relacionados con el acceso a Caldea y Likids. Una acci\u00f3n que ser\u00e1 muy espectacular y que se podr\u00e1 ver desde todos los rincones del pabell\u00f3n<\/p>\n<p>* Caldea repartir\u00e1n a los ni\u00f1os y ni\u00f1as pinturas para que puedan dibujarse la bandera tricolor en la cara. Y para los adultos, se repartir\u00e1n vales de 2&#215;1 en entrada de residentes, una promoci\u00f3n \u00fanica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partidazo ma\u00f1ana en la Bombonera. Por todo. El MoraBanc, que est\u00e1 en racha, recibe a las 20h30 el Divina Seguros Joventut de Badalona que est\u00e1 haciendo una temporada sensacional hasta ahora que la ha llevado a clasificarse para la Copa del Rey. Partidazo porque vendr\u00e1n muchos seguidores verdinegra y eso siempre dar color y m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":21511,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-21513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=21513"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/21511"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=21513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=21513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=21513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}