{"id":21548,"date":"2019-02-04T16:47:49","date_gmt":"2019-02-04T16:47:49","guid":{"rendered":"https:\/\/www.bca.ad\/previa-kazan-duelo-en-la-cumbre-por-la-primera-plaza\/"},"modified":"2019-02-04T16:47:49","modified_gmt":"2019-02-04T16:47:49","slug":"previa-kazan-duelo-en-la-cumbre-por-la-primera-plaza","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-kazan-duelo-en-la-cumbre-por-la-primera-plaza\/","title":{"rendered":"PREVIA KAZAN Duelo en la cumbre por la primera plaza"},"content":{"rendered":"<p><strong>Este mi\u00e9rcoles termina el Top16 de la Eurocup por MoraBanc Andorra y lo hace con un partido en el que est\u00e1 la primera plaza del grupo en juego en la pista del Unics Kazan (17h Tv en directo RTVA). Y hablar de acabar primero de grupo significa tener el factor cancha a favor en el primer playoff y seg\u00fan como vayan las cosas quiz\u00e1 tambi\u00e9n en los siguientes. Es decir que a pesar del recorrido para enmarcar los de Ibon Navarro hasta ahora (5 victorias en 5 partidos) el \u00faltimo tambi\u00e9n lo han de competir al m\u00e1ximo. Si el MoraBanc gana ser\u00e1 un primero de grupo incontestable con pleno de victorias. En caso de perder lo tiene que hacer por menos de 6 puntos de diferencia que en el partido que se jug\u00f3 en la Bombonera entre ambos conjuntos el resultado fue 86-80. M\u00e1xima ambici\u00f3n como ha habido hasta ahora en todo el recorrido europeo con toda la humildad del mundo para reconocer que el reto es may\u00fasculo porque, salvo la derrota en Andorra, el Unics ha sido muy s\u00f3lido toda la competici\u00f3n<\/strong> y ganar en su casa parece una tarea tit\u00e1nica. Pero si este reto ten\u00eda que llegar en alg\u00fan momento de la temporada a los de Ibon Navarro ahora parece el m\u00e1s apropiado para que las sensaciones del equipo son las mejores hasta ahora con mucha firmeza y consistencia como lo indican las 8 victorias seguidas que lleva el equipo o 10 de los \u00faltimos 11 partidos, una se\u00f1ora racha que en Kaz\u00e1n se querr\u00e1 seguir alimentando.<\/p>\n<p>El desplazamiento, como siempre que se va a Rusia ser\u00e1 muy largo y se puede decir que entre bus, aviones y diferencia horaria con el destino final, el viaje del equipo andorrano ma\u00f1ana hacia Kazan ser\u00e1 de alrededor de 16 horas. Se sabe, se cuenta, pero a m\u00e1xima exigencia siempre es un factor a comentar. Lo m\u00e1s interesante de la temporada del MoraBanc Andorra hasta ahora es que cuando ha sido, precisamente, m\u00e1s exigido es cuando lo ha hecho mejor. El peligro principal del Unics Kazan es su base Pierre Henry, Un director de juego grande y vers\u00e1til llamado a ser una estrella del baloncesto europeo si no marcha a la NBA. Contenerlo del todo sembvla casi imposible y habr\u00e1, al menos, que no juegue c\u00f3modo. El escolta, exUnicaja, Jamar Smith es una metralleta con la que habr\u00e1 que estar muy atentos tambi\u00e9n.<\/p>\n<p>Por parte tricolor Ibon Navarro podr\u00e1 contar con todos sus jugadores despu\u00e9s de muchas semanas en las que si no pasaba una pasaba otra. Es cierto que, por ejemplo, David Jel\u00ednek tiene el alta m\u00e9dica pero debe ir teniendo minutos para volver a ser el mismo de antes de la lesi\u00f3n en la rodilla.<\/p>\n<p>Hoy en la rueda de prensa previa al partido del mi\u00e9rcoles comparecieron Guille Colom Ibon Navarro.<\/p>\n<p><strong>Guille Colom<\/strong><\/p>\n<p><strong>Ser\u00e1 un partido muy importante para los dos equipos porque luchamos por la primera posici\u00f3n del grupo<\/strong>. Kazan es un gran equipo y tendremos que estar concentrados si queremos conseguir la victoria.<\/p>\n<p>Llegamos en un gran momento. Todos hemos entendido que si jugamos con la energ\u00eda necesaria y confiando en los compa\u00f1eros las cosas salen bien. Tenemos que jugar en Kazan as\u00ed, sin excusas y yendo a ganar.<\/p>\n<p>No pensaremos en el average, tenemos que ir a ganar y en todo caso eso s\u00f3lo lo mirar\u00edamos al final del partido &#8220;.<\/p>\n<p><strong>Ibon Navarro<\/strong><\/p>\n<p>Espero el mejor Unics, el que nos hizo un 0-12 para comenzar el partido que jugamos aqu\u00ed. Ellos jugando en casa buscar\u00e1n hacer su mejor partido para ser primeros y tenemos que hacer las cosas bien para poder competir al m\u00e1ximo en una pista muy dif\u00edcil, de un equipo de nivel de Euroliga.<\/p>\n<p>Tenemos que estar activos a nivel mental y no dejarnos ir en ning\u00fan momento.<\/p>\n<p><strong>La \u00fanica explicaci\u00f3n para la mejora es el trabajo. Y ser humildes e ir al l\u00edmite. En el momento en que lo olvidemos dejaremos de ganar y volveremos a caer. La clave es el trabajo, el del equipo y lo que han hecho muchos jugadores individualmente.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles termina el Top16 de la Eurocup por MoraBanc Andorra y lo hace con un partido en el que est\u00e1 la primera plaza del grupo en juego en la pista del Unics Kazan (17h Tv en directo RTVA). Y hablar de acabar primero de grupo significa tener el factor cancha a favor en el [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":21546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-21548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=21548"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/21546"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=21548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=21548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=21548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}