{"id":21559,"date":"2019-02-06T20:03:41","date_gmt":"2019-02-06T20:03:41","guid":{"rendered":"https:\/\/www.bca.ad\/72-53-derrota-en-kazan-segundos-de-grupo-y-playoff-de-villeurbanne\/"},"modified":"2019-02-06T20:07:40","modified_gmt":"2019-02-06T20:07:40","slug":"72-53-derrota-en-kazan-segundos-de-grupo-y-playoff-de-villeurbanne","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/72-53-derrota-en-kazan-segundos-de-grupo-y-playoff-de-villeurbanne\/","title":{"rendered":"(72-53) Derrota en Kazan, segundos de grupo y playoff contra Villeurbanne"},"content":{"rendered":"<p><strong>Segundos de grupo. No ha podido ser. Y poco m\u00e1s que decir, la cosa ha sido bastante clara hoy. El Unics Kazan ha derrotado al MoraBanc Andorra por 72-53 en uno de esos casta\u00f1azos que puedes acabar recibiendo cuando eres contestatario y rebelde con los grandes. Justo lo que llevan haciendo los tricolores durante todo el Top16. El resultado y la segunda plaza conlleva que en el playoff de cuartos de final de la 7Days Eurocup<\/strong> el rival sea el Asvel Villeurbanne franc\u00e9s, brillante primer clasificado de su grupo. Los franceses tendr\u00e1n el factor pista a favor. La eliminatoria comenzar\u00e1 a Villeurbanne (Lyon) el d\u00eda 5 de octubre. El partido de Andorra se jugar\u00e1 el viernes 8 y si hiciera falta un tercero se jugar\u00eda el mi\u00e9rcoles 13.<\/p>\n<p>Contrariamente a lo que dice el marcador, hoy ha habido partido. El MoraBanc se ha mantenido s\u00f3lido y firme durante 28 minutos. <strong>Los de Ibon Navarro sufr\u00edan ante la exhuberancia de los rusos pero segu\u00edan dentro del partido. El 43-42 que marcaba el electr\u00f3nico se ha ido a un 49-43 al final del 3Q.<\/strong> Y quiz\u00e1 porque estos 6 puntos marcaban la frontera de la lucha por el average, Unics ha cogido confianza. Exactamente lo contrario que el MoraBanc que se ha visto atrapado en la telara\u00f1a defensiva local. No aparec\u00edan soluciones en ataque, no como el primer cuarto que ha terminado 17-21. El tiro exterior ha visto afectada la punter\u00eda por la dureza defensiva y finalmente aplicarse en defensa no ha sido suficiente para contener la herida. La diferencia final explica, en parte, el partido. Si sirve para subrayar la incontestable superioridad local pero no la resistencia y el buen trabajo realizado durante muchos minutos por el equipo andorrano. Pero el baloncesto al m\u00e1ximo nivel si de algo falto es de piedad y si no est\u00e1s como toca te lo hacen saber. La traducci\u00f3n de ello son los 20 puntos que ha hecho el equipo en la segunda parte.<\/p>\n<p>A nivel individual ha habido tres jugadores que han sobresalido y, hay que decirlo, que han tenido poca compa\u00f1\u00eda hoy. Albicy ha sido muy bien con 10 puntos y 8 asistencias para 16 de valoraci\u00f3n, Shurna ha hecho 9 puntos y 4 rebotes por 15 de valoraci\u00f3n y el m\u00e1s valorado ha sido Moussa con 19 de valoraci\u00f3n por los 12 puntos y 5 rebotes que ha acreditado.<\/p>\n<p><strong>Ma\u00f1ana toca viajar y domingo a las 12h30 el equipo vuelve a tener un reto fenomenal delante, conquistar la pista del Movistar Estudiantes.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundos de grupo. No ha podido ser. Y poco m\u00e1s que decir, la cosa ha sido bastante clara hoy. El Unics Kazan ha derrotado al MoraBanc Andorra por 72-53 en uno de esos casta\u00f1azos que puedes acabar recibiendo cuando eres contestatario y rebelde con los grandes. Justo lo que llevan haciendo los tricolores durante todo [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":21557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-21559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=21559"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/21557"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=21559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=21559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=21559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}