{"id":21997,"date":"2019-04-12T09:42:40","date_gmt":"2019-04-12T09:42:40","guid":{"rendered":"https:\/\/www.bca.ad\/previa-baskonia-sin-complejos-en-una-pista-prohibida-hasta-ahora\/"},"modified":"2019-04-12T12:16:10","modified_gmt":"2019-04-12T12:16:10","slug":"previa-baskonia-sin-complejos-en-una-pista-prohibida-hasta-ahora","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-baskonia-sin-complejos-en-una-pista-prohibida-hasta-ahora\/","title":{"rendered":"PREVIA BASKONIA Sin complejos en una pista prohibida hasta ahora"},"content":{"rendered":"<p><strong>Todas las cosas en la vida tienen una primera vez. He temas que cuestan m\u00e1s y otros que cuestan menos pero con paciencia todo llega. Todo este discurso que siempre usa la gente sabia y vivida va de maravilla para introducir el partido que el s\u00e1bado juega el MoraBanc Andorra en la pista del Baskonia (18h Tv en directo en el canal 213 de la fibra Andorra Telecom), un lugar donde en las 4 temporadas previas siempre se ha perdido. Dando m\u00e1s o menos guerra pero el Buesa Arena no ha sido hasta ahora un lugar propicio para alegr\u00edas.<\/strong> En esto tiene que ver, m\u00e1s que ning\u00fan otro factor, que el rival es de un gran potencial y que, adem\u00e1s, suele ser muy s\u00f3lido en su casa. El partido de ma\u00f1ana no presenta ning\u00fan condicionante diferente en este sentido. Baskonia llega al partido recuperando jugadores (sobre todo Shengelia) y habi\u00e9ndose clasificado por playoff de una Euroliga muy especial porque la final4 se celebra precisamente en Vitoria.<br \/>\nPor lo tanto, reto de m\u00e1xima altura por un MoraBanc Andorra que llega habiendo tengan una buena semana, al menos sin los sobresaltos de la anterior en que los mareos de Moussa y la gastritis de sanas hicieron llegar el equipo muy mermado al partido contra Valencia . Los tricolores buscar\u00e1n dar una sorpresa que los colocar\u00eda en inmejorable situaci\u00f3n para un rush final en el que los hombres de Ibon Navarro tienen muchos enfrentamientos con rivales directos en la lucha por los playoffs. Tal y como est\u00e1 el calendario se puede afirmar sin problema que si el MoraBanc Andorra acaba jugando el playoff ser\u00e1 porque se lo ha merecido seguro porque Zaragoza viene a Andorra y se debe visitar Tenerife y Manresa.<\/p>\n<p>&#8220;Dylan Ennis se queda en Andorra para esperar el nacimiento de su hija&#8221; ha sido la declaraci\u00f3n m\u00e1s relevante de toda la rueda de prensa previa y una vez hecha Ibon Navarro a\u00f1adi\u00f3 enseguida que &#8220;el ni\u00f1o nacer\u00e1 este fin de semana y entendemos que lo mejor para el jugador es que est\u00e9 con su mujer sobre todo porque estamos hablando de una pareja que no tiene familia en Andorra &#8220;.<strong> Navarro no ha escondido que &#8220;a m\u00ed me gustar\u00eda contar con el jugador pero tendremos que encontrar la manera de jugar y ser competitivos sin el Dylan&#8221;. El t\u00e9cnico del MoraBanc Andorra no ha escondido que &#8220;nos espera un partido muy dif\u00edcil<\/strong> ante uno de los mejores equipos de Europa como lo demuestra el hecho de que jugar\u00e1n el playoff de la Euroliga donde s\u00f3lo se clasifican 8 equipos&#8221;. Sobre la estrategia a seguir, Navarro admite que &#8220;ser\u00e1 clave detener su juego a campo abierto&#8221;.<br \/>\nDavid Jel\u00ednek expuso que &#8220;tendremos que poner una energ\u00eda extra en este partido porque sabemos que jugamos contra un rival muy duro&#8221;<strong>. El escolta checo ha dicho tambi\u00e9n que &#8220;estamos pendientes del playoff y es inevitable mirar a ver c\u00f3mo est\u00e1n las cosas o el calendario que nos queda a los equipos pero lo que tenemos que hacer es estar centrados en ganar partidos&#8221;.<\/strong><\/p>\n<p><strong>Grandes emociones en lo que queda de competici\u00f3n empezando por compartir ma\u00f1ana con Ibon Navarro una nueva visita en su ciudad y en el lugar donde se hizo entrenador. Tambi\u00e9n ser\u00e1 especial la visita para Rafa Luz o para David Jel\u00ednek que han jugado a Baskonia.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las cosas en la vida tienen una primera vez. He temas que cuestan m\u00e1s y otros que cuestan menos pero con paciencia todo llega. Todo este discurso que siempre usa la gente sabia y vivida va de maravilla para introducir el partido que el s\u00e1bado juega el MoraBanc Andorra en la pista del Baskonia [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":21995,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-21997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=21997"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/21997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/21995"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=21997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=21997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=21997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}