{"id":23274,"date":"2019-10-04T12:11:56","date_gmt":"2019-10-04T12:11:56","guid":{"rendered":"https:\/\/www.bca.ad\/previa-barca-preparados-para-recibir-un-rival-temible\/"},"modified":"2019-10-04T15:21:00","modified_gmt":"2019-10-04T15:21:00","slug":"previa-barca-preparados-para-recibir-un-rival-temible","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-barca-preparados-para-recibir-un-rival-temible\/","title":{"rendered":"PREVIA BAR\u00c7A Preparados para recibir un rival temible"},"content":{"rendered":"\n<p><strong>Esta vez ha tocado temprano en el calendario la visita de uno de los grandes de la competici\u00f3n. Tercera jornada y a\u00fan con la casa un poco para arreglar pero con la ilusi\u00f3n de siempre por poder vivir unos enfrentamientos que para los aficionados tienen un sabor diferente. Especial. El MoraBanc Andorra juega el domingo a las 20h en la BMB contra el Bar\u00e7a en partido de la tercera jornada de la Liga Endesa.<\/strong> El Bar\u00e7a siempre es el Bar\u00e7a lo mires como lo mires y siempre es favorito en la liga espa\u00f1ola si no se enfrenta con el Madid, el equipo con el que hist\u00f3ricamente se ha repartido hegemon\u00edas y dinast\u00edas. Y por ah\u00ed va la cosa si se ha de entender el motivo por el que los azulgrana visitar\u00e1n la Bombonera con el proyecto m\u00e1s lujoso con diferencia del baloncesto europeo esta temporada. Un proyecto que los hace, no s\u00f3lo aspirar a todos los t\u00edtulos, sino, y esto debe ser lo m\u00e1s importante, querer romper el dominio del gran rival en la competici\u00f3n. El Madrid ha marcado la pauta en los \u00faltimos a\u00f1os y el Bar\u00e7a de Pesic, aunque hacer frente, quiere terminar amnb esto. Y para hacerlo este verano fich\u00f3 Higgins y Davies, dos de las estrellas m\u00e1s rutilantes de la Euroliga. Pero es que no contentos con ello fueron capaces de convencer Nicola Mirotic para volver a Europa y abandonar la NBA. Es un equipo glamouroso al tiempo que temible por los rivales. Domingo lo ser\u00e1 por MoraBanc Andorra.<\/p>\n\n<p>Pero. Siempre tiene que haber un pero. El partido se debe jugar y cuando empiecen a jugar ser\u00e1n 5 contra 5. Y en ese momento, sobre el parqu\u00e9 de la Bombonera, los tricolores tendr\u00e1n la oportunidad de complicar las cosas lo m\u00e1ximo posible a los visitantes. Los de Ibon Navarro llegan al partido tras una derrota clara en M\u00f3naco en el primer partido de la Eurocup y con la sensaci\u00f3n que queda trabajo por hacer para ajustar el talento y las ganas que indiscutiblemente tiene la plantilla. Es el cl\u00e1sico partido en el que la motivaci\u00f3n y las ganas est\u00e1n al m\u00e1ximo. Pase lo que pase, el equipo saldr\u00e1 a competir y agradar a los aficionados que llenar\u00e1n la Bombonera.<\/p>\n\n<p><strong>&#8220;Espero el mejor Bar\u00e7a&#8221; ha manifestado Ibon Navarro en rueda de prensa previa esta misma tarde y a\u00f1adi\u00f3 que si &#8220;no ve puntos d\u00e9biles en el rival y posiblemente tampoco nos ayudar\u00e1 el hecho de haber jugado dos partidos a cara o cruz en pretemporada contra ellos &#8220;.<\/strong> El t\u00e9cnico ha expuesto que lo que m\u00e1s le preocupa &#8220;de los partidos que hemos jugado hasta ahora son las p\u00e9rdidas de bal\u00f3n y el ritmo y estoy convencido de que si jugamos con m\u00e1s ritmo no tendremos m\u00e1s p\u00e9rdidas&#8221;. Ibon Navarro ha dicho tambi\u00e9n que &#8220;los jugadores nuevos en la liga estos partidos est\u00e1n siendo un proceso de adaptaci\u00f3n, algunos nos han dicho que nunca hab\u00edan jugado tres partidos consecutivos de este nivel&#8221;. Para el entrenador del MoraBanc Andorra la obejctiu Domingo ser\u00e1 &#8220;competir al m\u00e1s alto nivel contra el equipo de moda en Europa&#8221;.<\/p>\n\n<p><strong>Clevin Hannah tambi\u00e9n ha comparecido hoy y expuso que &#8220;el equipo hab\u00eda tenido unos d\u00edas dif\u00edciles despu\u00e9s de una dura derrota europea y que hab\u00edan trabajado duro en conceptos como tener m\u00e1s cuidado de la pelota y de compartirla<\/strong>&#8220;. Hannah ha sido exigente consigo mismo y su rendimiento hasta afirmando que &#8220;tengo que mejorar sobre todo en las p\u00e9rdidas de bal\u00f3n&#8221;. Hannah ha expuesto tambi\u00e9n que &#8220;jugamos contra un gran equipo lleno de grandes jugadores eso seguro, y el gran desaf\u00edo para todos es competir al m\u00e1ximo nivel contra ellos&#8221;.<\/p>\n\n<p><strong>En pretemporada ambos equipos se enfrentaron dos veces con una victoria para cada lado. Domingo ya ir\u00e1 de verdad.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta vez ha tocado temprano en el calendario la visita de uno de los grandes de la competici\u00f3n. Tercera jornada y a\u00fan con la casa un poco para arreglar pero con la ilusi\u00f3n de siempre por poder vivir unos enfrentamientos que para los aficionados tienen un sabor diferente. Especial. El MoraBanc Andorra juega el domingo [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":23282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109],"tags":[],"class_list":["post-23274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/23274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=23274"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/23274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/23282"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=23274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=23274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=23274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}