{"id":24062,"date":"2019-10-25T13:44:47","date_gmt":"2019-10-25T13:44:47","guid":{"rendered":"https:\/\/www.bca.ad\/previa-betis-visita-a-un-rival-con-mas-juego-que-resultados\/"},"modified":"2019-10-25T13:44:47","modified_gmt":"2019-10-25T13:44:47","slug":"previa-betis-visita-a-un-rival-con-mas-juego-que-resultados","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-betis-visita-a-un-rival-con-mas-juego-que-resultados\/","title":{"rendered":"PREVIA BETIS Visita a un rival con m\u00e1s juego que resultados"},"content":{"rendered":"\n<p><strong>Para el Bc MoraBanc Andorra el partido del domingo en la pista del Coosur Betis de Sevilla (17h, TV en directo en el 213 de la fibra Andorra Telecom) llega en un buen momento por qu\u00e9 los de Ibon Navarro han encadenado dos victorias consecutivas y vienen de obtener el primer triunfo fuera de la temporada. El Betis es un reci\u00e9n ascendido y en esa pista el MoraBanc ha ganado dos veces y tambi\u00e9n ha perdido otros dos<\/strong>. En San Pablo espera a los tricolores un equipo que est\u00e1 jugando muy buen baloncesto y que tiene menos victorias de las que merece porque ha perdido un partido en el \u00faltimo segundo y tambi\u00e9n vio el fin de semana pasado como Baskonia le remontaba en Vitoria un partido que ten\u00eda bastante controlado. Por lo tanto, un d\u00eda m\u00e1s, partido complicado porqu\u00e9 los de Curro Segura tienen marcado el partido en rojo para obtener una victoria que les permita respirar. El nivel de la plantilla del Betis da pie a explicar el aumento de nivel de la Liga Endesa esta temporada. Con los verdiblancos juega Kc Rivers, un exMadrid entre otros clubes de Euroliga y con una izquierda de seda. Por dentro la referencia es Shayne Whittington, que fue tricolor unos meses la temporada pasada, y que est\u00e1 jugando a gran nivel. En una plantilla de gran talento destaca la presencia de Albert Oliver que pasados \u200b\u200blos 40 a\u00f1os demuestra cada partido su magisterio y liderazgo. Tambi\u00e9n es b\u00e9tico Nacho Mart\u00edn, otro exMoraBanc.<\/p>\n\n<p><p><strong>Por lo tanto los de Ibon Navarro ya saben que tendr\u00e1n que hacer un gran partido para ganar en Sevilla.<\/strong> La buena noticia es que es posible, no seguro, que Dejan Musli juegue y desde ayer ya est\u00e1 en Andorra de nuevo Jeremy Senglin que se fue a los Estados Unidos a conocer su hija Alani que naci\u00f3 hace dos semanas. Una victoria del MoraBanc le permitir\u00eda sacar la cabeza todav\u00eda con m\u00e1s fuerza en la parte alta de la clasificaci\u00f3n, donde ahora mismo ocupa el 8\u00ba lugar. El equipo viaja ma\u00f1ana hacia Sevilla y la rueda de prensa previa se ha celebrado este mediod\u00eda en el stand del club en la Feria de Andorra la Vella. &#8220;Es un equipo complicado porque su juego en casa est\u00e1 siendo bueno incluso en los partidos que han perdido, es un equipo que seguro que ser\u00e1 complicado&#8221; afirm\u00f3 el entrenador ayudante Paco V\u00e1zquez que sobre el MoraBanc expuso que &#8221; se tratar\u00e1 de hacer un partido serio como el que hicimos en Israel &#8220;. V\u00e1zquez cree que &#8220;el equipo est\u00e1 creyendo en lo que est\u00e1 haciendo y esto aumenta siempre nuestras posibilidades de ganar&#8221;. &#8220;El Betis ha fichado jugadores de calidad y los resultados no les est\u00e1n acompa\u00f1ando para el juego que est\u00e1n haciendo&#8221; concluy\u00f3 V\u00e1zquez. &#8220;Fue importante conseguir la primera victoria fuera, lo fue para la confianza del equipo&#8221; afirm\u00f3 Frantz Massenat, que ha a\u00f1adido que &#8220;personalmente tambi\u00e9n fue bueno para mi confianza el partido del martes en Israel, el t\u00e9cnico siempre me dijo que siguiera trabajando duro y en mi caso se trata de seguir jugando como siempre y conseguir llegar a disfrutar en la pista &#8220;.<br\/><br\/><\/p><\/p>\n\n<p>Tras el partido de este domingo en Sevilla, al MoraBanc Andorra le vendr\u00e1n tres partidos seguidos en casa contra Promitheas Patras, UCAM Murcia y AS M\u00f3naco.&#13;\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el Bc MoraBanc Andorra el partido del domingo en la pista del Coosur Betis de Sevilla (17h, TV en directo en el 213 de la fibra Andorra Telecom) llega en un buen momento por qu\u00e9 los de Ibon Navarro han encadenado dos victorias consecutivas y vienen de obtener el primer triunfo fuera de la [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":24060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109],"tags":[],"class_list":["post-24062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/24062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=24062"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/24062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/24060"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=24062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=24062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=24062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}