{"id":24861,"date":"2019-12-19T18:24:06","date_gmt":"2019-12-19T18:24:06","guid":{"rendered":"https:\/\/www.bca.ad\/ya-tenemos-calendario-para-el-spanish-top16-eurocup\/"},"modified":"2019-12-22T12:48:47","modified_gmt":"2019-12-22T12:48:47","slug":"ya-tenemos-calendario-para-el-spanish-top16-eurocup","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/ya-tenemos-calendario-para-el-spanish-top16-eurocup\/","title":{"rendered":"Ya tenemos calendario para el spanish Top16 Eurocup"},"content":{"rendered":"\n<p>El MoraBanc Andorra deber\u00e1 afrontar un Top16 Eurocup a la espa\u00f1ola y de gran dificultad. La segunda de las afirmaciones es un t\u00f3pico porque a medida que se avanza en la competici\u00f3n las dificultades van siempre con el precio. En este caso el grupo del MoraBanc Andorra en el Top16 es el H al que accede como el segundo del grupo A y los hombres de Ibon Navarro se enfrentar\u00e1n con Unicaja de M\u00e1laga (campe\u00f3n del grupo D), con el Tofa\u015f Bursa ( tercero del grupo B) y con el Joventut de Badalona (cuarto del grupo D). La competici\u00f3n vuelve a empezar &#8220;con una liguilla muy corta en la que los errores se pagan muy caros&#8221; afirma el General Manager Francesc Solana que a\u00f1ade que &#8220;quiz\u00e1s por el p\u00fablico puede resultar menos atractivo jugar contra equipos de la liga Endesa en Europa pero todo tiene sus cosas buenas y malas, en este caso las buenas son los viajes que son m\u00e1s cortos&#8221;.<\/p>\n\n<p>Este es el calendario del Top 16 por MoraBanc Andorra:<\/p>\n\n<p>8 de enero 20h45&#13;\n<\/p>\n\n<p>Joventut de Badalona-MoraBanc Andorra<\/p>\n\n<p>15 de enero 20h<\/p>\n\n<p>MoraBanc Andorra- Tofa\u015f Bursa<\/p>\n\n<p>21 de enero 20h<\/p>\n\n<p>MoraBanc Andorra-Unicaja de M\u00e1laga<\/p>\n\n<p>29 de enero 20h45<\/p>\n\n<p>Unicaja de M\u00e1laga-MoraBanc Andorra<\/p>\n\n<p>4 de febrero 20h<\/p>\n\n<p>MoraBanc Andorra-Joventut de Badalona<\/p>\n\n<p>4 de marzo 18h<\/p>\n\n<p>Tofa\u015f Bursa-MoraBanc Andorra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El MoraBanc Andorra deber\u00e1 afrontar un Top16 Eurocup a la espa\u00f1ola y de gran dificultad. La segunda de las afirmaciones es un t\u00f3pico porque a medida que se avanza en la competici\u00f3n las dificultades van siempre con el precio. En este caso el grupo del MoraBanc Andorra en el Top16 es el H al que [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":24860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109,98],"tags":[],"class_list":["post-24861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es","category-noticia-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/24861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=24861"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/24861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/24860"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=24861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=24861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=24861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}