{"id":25959,"date":"2020-08-18T11:41:41","date_gmt":"2020-08-18T11:41:41","guid":{"rendered":"https:\/\/www.bca.ad\/pauli-y-sergi-presentan-credenciales-para-ser-importantes\/"},"modified":"2020-08-18T11:41:42","modified_gmt":"2020-08-18T11:41:42","slug":"pauli-y-sergi-presentan-credenciales-para-ser-importantes","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/pauli-y-sergi-presentan-credenciales-para-ser-importantes\/","title":{"rendered":"Paul\u00ed y Sergi presentan credenciales para ser importantes"},"content":{"rendered":"\n<p>En los tiempos del Covid todo parece diferente pero al mismo tiempo se debe luchar para no perder las buenas costumbres. Adapt\u00e1ndolas eso s\u00ed, a las medidas sanitarias y las precauciones que indican las autoridades. En este contexto, y en la sede central de MoraBanc se ha celebrado la primera presentaci\u00f3n de fichajes de esta temporada. Los siempre positivos Oriol Paul\u00ed y Sergi Garcia han visto ocultadas sus sonrisas por una mascarilla pero en sus miradas ha quedado bien claro que vislumbran un futuro lleno de \u00e9xitos en el MoraBanc Andorra. Los dos jugadores, adem\u00e1s, parecen tener un punto en com\u00fan y es que la etapa tricolor est\u00e1 bien subrayada como en la que tienen que dar un gran salto de calidad a sus carreras y es con esta ambici\u00f3n con la que aterrizan en el equipo de Ibon Navarro.<\/p>\n\n<p><strong>&#8220;Incorporamos dos jugadores con una perspectiva de futuro muy buena pero no los fichamos por ello sino que lo hacemos por el presente y por la gran influencia<\/strong> que pueden tener en el juego del equipo&#8221; ha manifestado el <strong>General Manager Francesc Solana<\/strong> en la rueda de prensa de presentaci\u00f3n de hoy, en la que ha a\u00f1adido que &#8220;esperamos que encuentren en Andorra el lugar en el que desarrollar todo su talento con firmeza y continuidad&#8221;.<strong> Oriol Paul\u00ed ha seguido en la misma l\u00ednea afirmando que &#8220;es cierto que llevamos una buena carrera pero estamos buscando una continuidad y creo que aqu\u00ed la podemos encontrar&#8221;<\/strong>. Garcia ha expuesto que &#8220;este club ha ido creciendo a\u00f1o tras a\u00f1o en las competiciones que disputa y tenemos mucha ilusi\u00f3n por venir aqu\u00ed a crecer como jugadores y dar un paso adelante&#8221;. El base tambi\u00e9n ha dicho que &#8220;se ha hecho un gran grupo para conseguirlo, Andorra me puede dar esta continuidad y tengo muchas ganas de empezar a trabajar por los objetivos del equipo y por mis&#8221;. Paul\u00ed ha destacado que &#8220;el crecimiento del MoraBanc Andorra en las \u00faltimas temporadas es uno de los elementos que te hace decidir porque es un club que se ve que tiene mucha ambici\u00f3n y que apuesta por nosotros&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los tiempos del Covid todo parece diferente pero al mismo tiempo se debe luchar para no perder las buenas costumbres. Adapt\u00e1ndolas eso s\u00ed, a las medidas sanitarias y las precauciones que indican las autoridades. En este contexto, y en la sede central de MoraBanc se ha celebrado la primera presentaci\u00f3n de fichajes de esta [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":25958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-25959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/25959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=25959"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/25959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/25958"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=25959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=25959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=25959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}