{"id":27085,"date":"2021-01-08T10:18:59","date_gmt":"2021-01-08T10:18:59","guid":{"rendered":"https:\/\/www.bca.ad\/previa-fuenla-partido-importante-para-cambiar-la-dinamica\/"},"modified":"2021-01-08T10:18:59","modified_gmt":"2021-01-08T10:18:59","slug":"previa-fuenla-partido-importante-para-cambiar-la-dinamica","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-fuenla-partido-importante-para-cambiar-la-dinamica\/","title":{"rendered":"PREVIA FUENLA Partido importante para cambiar la din\u00e1mica"},"content":{"rendered":"\n<p>El MoraBanc Andorra siente que se despeja un poco el panorama despu\u00e9s de un mes que ha sido una aut\u00e9ntica locura de partidos. Un mes que comenz\u00f3 plet\u00f3rico y acab\u00f3 en complicado y con mala racha de resultados.<strong> Los de Ibon Navarro juegan ma\u00f1ana a las 20h45 (Tv en directo al 272 de la fibra Andorra Telecom) en la pista del Urbas Fuenlabrada en el partido que cierra la primera vuelta de la competici\u00f3n. Hay que poner un asterisco en esta afirmaci\u00f3n porque al equipo le faltar\u00e1 el partido que deb\u00eda jugar el jueves en casa contra Monb\u00fas Obradoiro y que se ha aplazado por el brote de Covid del equipo gallego. Ma\u00f1ana se enfrentan dos equipos necesitados de alegr\u00edas. En el caso de los tricolores por qu\u00e9 la din\u00e1mica no es buena y para empezar un nuevo tramo de temporada con buenas sensaciones y nuevas aspiraciones.<\/strong> En el caso de los locales porque han tenido de todo hasta ahora, empezaron muy mal, despu\u00e9s estuvieron muy bien y ahora vuelven a necesitar un nuevo impulso. Quiz\u00e1 por eso Urbas Fuenlabrada ha hecho tantos cambios en el equipo. Incluyendo el entrenador, Javi Juarez que sustituy\u00f3 a Paco Garc\u00eda, los madrile\u00f1os han hecho ya 7 cambios manteniendo, eso s\u00ed, dos hombres como term\u00f3metro en el ataque, los muy peligrosos Marc Garcia y Mello Trimble. Por parte del MoraBanc Andorra, la semana ha sido la mejor de las \u00faltimas en cuanto a los entrenamientos pot qu\u00e9 Tyson y Dim\u00e8 han vuelto a los entrenamientos y ya s\u00f3lo queda Moussa fuera de la din\u00e1mica del equipo por lesi\u00f3n. Parakhouski tambi\u00e9n ha tenido m\u00e1s d\u00edas para ir adapt\u00e1ndose al equipo. La sensaci\u00f3n en el grupo es que ahora se abre un nuevo horizonte y hay que estar preparados para avanzar en buenas condiciones.<\/p>\n\n<p><strong>&#8220;Es un partido importante para nosotros y para ellos tambi\u00e9n&#8221; ha expuesto en rueda de prensa Paco V\u00e1zquez que ha manifestado tambi\u00e9n que &#8220;Fuenlabrada ha hecho cambios de jugadores recientemente y eso nos dificultar\u00e1 m\u00e1s saber el equipo que nos encontraremos delante&#8221;<\/strong>. El t\u00e9cnico ayudante ha referido al mes de diciembre como &#8220;una tormenta de partidos que hemos dejado atr\u00e1s&#8221;. Para Nacho V\u00e1zquez la clave del partido estar\u00e1 en &#8220;hacer bien nuestras cosas y en recuperar la solidez defensiva de los partidos en los que hemos estado bien&#8221;. El p\u00edvot ha dicho que &#8220;la moral del equipo est\u00e1 bien y con ganas de abrir una nueva din\u00e1mica positiva de resultados&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El MoraBanc Andorra siente que se despeja un poco el panorama despu\u00e9s de un mes que ha sido una aut\u00e9ntica locura de partidos. Un mes que comenz\u00f3 plet\u00f3rico y acab\u00f3 en complicado y con mala racha de resultados. Los de Ibon Navarro juegan ma\u00f1ana a las 20h45 (Tv en directo al 272 de la fibra [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":27084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[],"class_list":["post-27085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/27085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=27085"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/27085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/27084"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=27085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=27085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=27085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}