{"id":28360,"date":"2021-06-18T18:41:08","date_gmt":"2021-06-18T18:41:08","guid":{"rendered":"https:\/\/www.bca.ad\/somos-eurocup\/"},"modified":"2021-06-18T18:41:08","modified_gmt":"2021-06-18T18:41:08","slug":"somos-eurocup","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/somos-eurocup\/","title":{"rendered":"Somos Eurocup"},"content":{"rendered":"\n<p><strong>Somos Eurocup<\/strong>. El MoraBanc Andorra volver\u00e1 a competir la pr\u00f3xima temporada (ser\u00e1 la quinta consecutiva) en la segunda competici\u00f3n m\u00e1s importante del baloncesto europeo. &#8220;Formaremos parte de una lista de 20 equipos muy importantes s\u00f3lo por detr\u00e1s de los 18 que juegan Euroliga y seguir aqu\u00ed para nosotros es importante&#8221; afirm\u00f3 el presidente Gorka Aix\u00e0s, que tambi\u00e9n ha dicho que &#8220;es un hecho destacado para nosotros poder ya asegurar a nuestros aficionados que la pr\u00f3xima temporada de vuelta al pabell\u00f3n volveremos a contar con competici\u00f3n europea &#8220;. Aparte del<strong> MoraBanc Andorra<\/strong> los equipos participantes en la pr\u00f3xima Eurocup son <strong>Promitheas Patras, Lokomotiv Kuban Krasnodar, Buducnost Voli Podgorica, Partizan NIS Belgrade, Virtus Bolonia, Lietkabelis, Cedevita Olimpija Ljubljana, Dolomiti Energ\u00eda Trento, Boulogne Metropolitanos 92, JL Bourg en Bresse, Ratiopharm Ulm, Turk Telekom, Frutti Extra Bursaspor, Hamburgo Towers, Humana Reyer Venice, Slask Wroclaw, Valencia Basket, Herbalife Gran Canaria y Joventut de Badalona.<\/strong> El d\u00eda 9 de julio se sabr\u00e1 c\u00f3mo queda la composici\u00f3n de cada uno de los dos grupos. El mejor resultado del MoraBanc Andorra a Eurocup han sido las semifinales de la temporada 2018\/19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Somos Eurocup. El MoraBanc Andorra volver\u00e1 a competir la pr\u00f3xima temporada (ser\u00e1 la quinta consecutiva) en la segunda competici\u00f3n m\u00e1s importante del baloncesto europeo. &#8220;Formaremos parte de una lista de 20 equipos muy importantes s\u00f3lo por detr\u00e1s de los 18 que juegan Euroliga y seguir aqu\u00ed para nosotros es importante&#8221; afirm\u00f3 el presidente Gorka Aix\u00e0s, [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":28359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944],"tags":[],"class_list":["post-28360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/28360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=28360"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/28360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/28359"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=28360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=28360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=28360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}