{"id":32201,"date":"2023-01-02T15:47:16","date_gmt":"2023-01-02T15:47:16","guid":{"rendered":"https:\/\/www.bca.ad\/pal-arinsal-renueva-como-colaborador-oficial\/"},"modified":"2023-01-02T15:47:16","modified_gmt":"2023-01-02T15:47:16","slug":"pal-arinsal-renueva-como-colaborador-oficial","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/pal-arinsal-renueva-como-colaborador-oficial\/","title":{"rendered":"PAL ARINSAL RENUEVA COMO COLABORADOR OFICIAL"},"content":{"rendered":"\n<p><strong>La estaci\u00f3n Pal Arinsal Grandvalira Resorts continuar\u00e1 como colaborador oficial del equipo de BC MoraBanc Andorra<\/strong>. Ambas instituciones de referencia en el mundo deportivo andorrano han llegado a un acuerdo para alargar su colaboraci\u00f3n.<\/p>\n\n<p>Con este nuevo acuerdo, la estaci\u00f3n de la Massana sigue junto al equipo en una nueva temporada ilusionante, y con los m\u00e1ximos retos de antemano. La colaboraci\u00f3n permite al BCA recibir el apoyo del dominio para seguir luchando por los grandes objetivos, mientras que Pal Arinsal Grandvalira Resorts estar\u00e1 presente en la equipaci\u00f3n de juego, concretamente en el pantal\u00f3n, para dar la m\u00e1xima difusi\u00f3n, tanto en las pistas de la Liga Leb Oro como en las retransmisiones televisivas.<\/p>\n\n<p><strong>Se trata de una asociaci\u00f3n entre dos de las entidades m\u00e1s importantes del mundo del deporte en Andorra con la que, adem\u00e1s, se potencia la marca en un territorio objetivo.<\/strong><\/p>\n\n<p>El presidente del MoraBanc Andorra, Gorka Aix\u00e0s, ha agradecido el apoyo recibido desde Pal Arinsal Grandvalira Resorts. Aix\u00e0s ve en esta nueva colaboraci\u00f3n un acto de distinci\u00f3n del recorrido del equipo y asegura que el BCA siempre debe estar ligado con las marcas m\u00e1s importantes del pa\u00eds y sobre todo, en aquellas que suponen sumar por el pa\u00eds fuera de las nuestras fronteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estaci\u00f3n Pal Arinsal Grandvalira Resorts continuar\u00e1 como colaborador oficial del equipo de BC MoraBanc Andorra. Ambas instituciones de referencia en el mundo deportivo andorrano han llegado a un acuerdo para alargar su colaboraci\u00f3n. Con este nuevo acuerdo, la estaci\u00f3n de la Massana sigue junto al equipo en una nueva temporada ilusionante, y con los [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":32200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150],"tags":[],"class_list":["post-32201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/32201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=32201"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/32201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/32200"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=32201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=32201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=32201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}