{"id":33282,"date":"2023-08-03T12:18:35","date_gmt":"2023-08-03T10:18:35","guid":{"rendered":"https:\/\/www.bca.ad\/el-morabanc-andorra-ya-conoce-la-hoja-de-ruta-de-la-vuelta-a-la-acb\/"},"modified":"2023-08-03T12:19:53","modified_gmt":"2023-08-03T10:19:53","slug":"calendario-acb-2023-2024","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/calendario-acb-2023-2024\/","title":{"rendered":"El MoraBanc Andorra ya conoce la hoja de ruta de la vuelta a la ACB"},"content":{"rendered":"<p style=\"text-align: justify;\">La Liga Endesa arrancar\u00e1 para el BC MoraBanc Andorra el d\u00eda 24 de setiembre (17:00h) en la pista del Surne Bilbao Basket seg\u00fan el calendario que acaba de hacer p\u00fablico la ACB. La Bombonera entrar\u00e1 en juego a grandes dosis, ya que tendremos las visitas del R\u00edo Breog\u00e1n el viernes 29 de setiembre (20:30h) y la del reci\u00e9n ascendido Zunder Palencia el domingo 1 de octubre (17:00h). Uno de los platos fuertes llegar\u00e1 en seguida con la visita del MoraBanc Andorra en la pista del Bar\u00e7a, donde se enfrentar\u00e1 al equipo azulgrana el domingo 8 de octubre (12:30h). En esta primera vuelta podemos destacar la visita del Real Madrid a Andorra, programada para el domingo 26 de noviembre (12:30h). El \u00faltimo partido de la primera vuelta ser\u00e1 con la visita del UCAM Murcia en la Bombonera, justo el D\u00eda de Reyes (s\u00e1bado 6 de enero a las 18:00h). Este ser\u00e1 el \u00faltimo partido antes del corte para la Copa. En la segunda vuelta, la visita del Bar\u00e7a, vigente campe\u00f3n, para el domingo 28 de abril a las 18:30 horas. Para MoraBanc Andorra, la liga regular acabar\u00e1 visitando el 10 de mayo al R\u00edo Breog\u00e1n y recibiendo en casa el 11\/12 de mayo al Valencia Basket.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Liga Endesa arrancar\u00e1 para el BC MoraBanc Andorra el d\u00eda 24 de setiembre (17:00h) en la pista del Surne Bilbao Basket seg\u00fan el calendario que acaba de hacer p\u00fablico la ACB. La Bombonera entrar\u00e1 en juego a grandes dosis, ya que tendremos las visitas del R\u00edo Breog\u00e1n el viernes 29 de setiembre (20:30h) y [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":33281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,109],"tags":[1037,521],"class_list":["post-33282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-morabanc-andorra-es","tag-acb-es-2","tag-morabanc-andorra-es2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/33282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=33282"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/33282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/33281"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=33282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=33282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=33282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}