{"id":33987,"date":"2023-11-23T17:33:50","date_gmt":"2023-11-23T15:33:50","guid":{"rendered":"https:\/\/www.bca.ad\/seguimos-luchando-contra-la-violencia-hacia-las-mujeres\/"},"modified":"2023-11-23T17:36:45","modified_gmt":"2023-11-23T15:36:45","slug":"seguimos-luchando-contra-la-violencia-hacia-las-mujeres-25n-23-24","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/seguimos-luchando-contra-la-violencia-hacia-las-mujeres-25n-23-24\/","title":{"rendered":"Seguimos luchando contra la violencia hacia las mujeres"},"content":{"rendered":"<p style=\"text-align: justify;\">El pr\u00f3ximo 25 de noviembre se celebra el d\u00eda Internacional para la eliminaci\u00f3n de la violencia contra las mujeres. Por este motivo, el BC MoraBanc Andorra, la Secretar\u00eda de Estado de Igualdad y Participaci\u00f3n Ciudadana y el Ministerio de Asuntos Sociales y Funci\u00f3n P\u00fablica del Gobierno de Andorra vuelven a unir esfuerzos para seguir luchando contra la violencia hacia las mujeres.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Con el lema &#8216;Nosotros luchamos contra la violencia hacia las mujeres. \u00bfTe apuntas? #Maipor25N&#8217; queremos seguir pasando el mensaje de que esta es una lucha que nos afecta a todos y a todas y que va m\u00e1s all\u00e1 de un solo d\u00eda. Para ello, el club y el Gobierno de Andorra han preparado una serie de acciones. La primera, y m\u00e1s significativa, el primer equipo vestir\u00e1 de lila (color reivindicativo a favor de la igualdad de g\u00e9nero) durante el partido que tendr\u00e1 lugar en Madrid el pr\u00f3ximo 26 de Noviembre ante el Real Madrid y el pr\u00f3ximo 9 de Diciembre en el enfrentamiento en casa ante el Unicaja de M\u00e1laga.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Unas camisetas, las que utilizar\u00e1n los jugadores de Natxo Lezkano, que se pondr\u00e1n a subasta mediante Gol Solidario durante los 15 d\u00edas que hay entre un partido y otro partido. Los beneficios obtenidos se destinar\u00e1n a las asociaciones de mujeres de Andorra. Cada d\u00eda, desde el lunes 27, una camiseta de uno de los jugadores. As\u00ed hasta el 8 de Diciembre, d\u00eda previo al partido de la jornada 13.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, durante esta quincena, cada jugador del primer equipo lanzar\u00e1 un mensaje diario para la lucha contra la violencia hacia las mujeres. Reforzando la campa\u00f1a liderada por el Gobierno de Andorra.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo, en el partido ante el Unicaja de M\u00e1laga, tambi\u00e9n se podr\u00e1n adquirir las r\u00e9plicas de las camisetas utilizadas. Una recaudaci\u00f3n que, como la subasta del primer equipo, ir\u00e1 destinada a las asociaciones de mujeres de Andorra. La idea, que todo el mundo pueda adquirir esta edici\u00f3n especial de la camiseta, y ayude a la eliminaci\u00f3n de la violencia hacia las mujeres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 25 de noviembre se celebra el d\u00eda Internacional para la eliminaci\u00f3n de la violencia contra las mujeres. Por este motivo, el BC MoraBanc Andorra, la Secretar\u00eda de Estado de Igualdad y Participaci\u00f3n Ciudadana y el Ministerio de Asuntos Sociales y Funci\u00f3n P\u00fablica del Gobierno de Andorra vuelven a unir esfuerzos para seguir luchando [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":33986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109],"tags":[1239,205,1059],"class_list":["post-33987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es","tag-25n-es","tag-morabanc-andorra","tag-temporada-2023-2024-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/33987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=33987"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/33987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/33986"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=33987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=33987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=33987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}