{"id":34450,"date":"2023-12-15T13:02:50","date_gmt":"2023-12-15T11:02:50","guid":{"rendered":"https:\/\/www.bca.ad\/ya-disponible-el-abono-de-segunda-vuelta\/"},"modified":"2023-12-15T13:06:54","modified_gmt":"2023-12-15T11:06:54","slug":"ya-disponible-el-abono-de-segunda-vuelta-23-24","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/ya-disponible-el-abono-de-segunda-vuelta-23-24\/","title":{"rendered":"Ya disponible el Abono de Segunda Vuelta"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>La segunda vuelta de la temporada 2023-2024 se presenta de lo m\u00e1s interesante y atractiva. Una segunda vuelta que har\u00e1 de nuestro &#8220;Joc de Grans&#8221; una m\u00e1xima.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Si ya era antes de los cambios de calendario, ahora lo es mucho m\u00e1s con la visita de los dos grandes a la Bombonera. Tanto el Bar\u00e7a como el Real Madrid pisar\u00e1n tierras andorranas en la segunda parte de la temporada. Un calendario que adem\u00e1s, debe sumarse la visita de Valencia, Joventut o Girona. Una segunda vuelta con todo en juego y que necesitaremos una Bombonera llena para alcanzar los grandes retos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">No lo pienses, abonate al MoraBanc Andorra. Lo podr\u00e1s hacer al 50% y disfrutar\u00e1s de todos los partidos de la segunda vuelta, pero adem\u00e1s te regalamos dos partidos extras para finalizar la primera vuelta. Dreamland Gran Canaria y UCAM Murcia gratis. Para que calientes motores para lo que vendr\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u00a1No lo dudes, disfruta de la Liga Endesa y del MoraBanc Andorra en la BMB!<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Lo puedes hacer v\u00eda online rellenando el formulario pero tambi\u00e9n puedes informarte en las oficinas del club, en el tel\u00e9fono 885900 o por correo electr\u00f3nico abonaments@bca.ad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La segunda vuelta de la temporada 2023-2024 se presenta de lo m\u00e1s interesante y atractiva. Una segunda vuelta que har\u00e1 de nuestro &#8220;Joc de Grans&#8221; una m\u00e1xima. &nbsp; Si ya era antes de los cambios de calendario, ahora lo es mucho m\u00e1s con la visita de los dos grandes a la Bombonera. Tanto el Bar\u00e7a [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":34449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109],"tags":[],"class_list":["post-34450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/34450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=34450"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/34450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/34449"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=34450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=34450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=34450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}