{"id":35215,"date":"2024-06-28T13:00:30","date_gmt":"2024-06-28T11:00:30","guid":{"rendered":"https:\/\/www.bca.ad\/el-bc-morabanc-andorra-y-kappa-unen-fuerzas\/"},"modified":"2024-06-28T13:19:10","modified_gmt":"2024-06-28T11:19:10","slug":"acuerdo-bc-morabanc-andorra-kappa-24-26","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/acuerdo-bc-morabanc-andorra-kappa-24-26\/","title":{"rendered":"El BC MoraBanc Andorra y Kappa unen fuerzas"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>El B\u00e0squet Club MoraBanc Andorra y Kappa han llegado a un acuerdo de alianza para que la marca deportiva sea el Patrocinador t\u00e9cnico oficial por las siguientes dos temporadas: 2024\/2025 y 2025\/2026.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Mediante este acuerdo, Kappa vestir\u00e1 al equipo en todas sus competiciones y proporcionar\u00e1 material t\u00e9cnico necesario para los entrenamientos y partidos. Esta colaboraci\u00f3n se fundamenta en los valores compartidos: pasi\u00f3n por el deporte, la excelencia y la innovaci\u00f3n, entre ambas entidades que permiten crear una sinergia positiva en torno al baloncesto y junto el proyecto de referencia del deporte de la canasta en Andorra.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El <strong>presidente del club<\/strong>, <strong>Gorka Aix\u00e0s<\/strong>, coment\u00f3 <strong>\u201cNos unimos a Kappa durante las pr\u00f3ximas temporadas. \u00c9poca de grandes retos para la entidad y que estamos seguros de que junto a una marca de referencia las podremos afrontar de la mejor manera posible\u201d<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Por su parte, desde <strong>Kappa<\/strong>, <strong>Daniel Gonz\u00e1lez<\/strong>, <strong>Sports Marketing &#038; TeamSport Manager<\/strong>, mostr\u00f3 su <strong>entusiasmo con la colaboraci\u00f3n y reforzo el compromiso de trabajar codo a codo con MoraBanc Andorra para alcanzar los objetivos marcados para las siguientes dos temporadas<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Con este acuerdo se refuerza el compromiso de la marca y del Club con el deporte, asegurando una colaboraci\u00f3n fruct\u00edfera que beneficiar\u00e1 a todo un proyecto de Pa\u00eds.<\/p>\n<p>&nbsp;<br \/>\n\n\t\t\t<!-- START kappaslider REVOLUTION SLIDER 6.7.36 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_16_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_16_1\" style=\"\" data-version=\"6.7.36\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-332\" data-title=\"Slide\" data-thumb=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_01_OK-50x100.jpg\" data-anim=\"ms:1000;r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bca.ad\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"signatura_kappa_01_OK\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_01_OK.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-333\" data-title=\"Slide\" data-thumb=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_02_OK-50x100.jpg\" data-anim=\"ms:1000;r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bca.ad\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"signatura_kappa_02_OK\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_02_OK.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-334\" data-title=\"Slide\" data-thumb=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_03_OK-50x100.jpg\" data-anim=\"ms:1000;r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bca.ad\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"signatura_kappa_03_OK\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_03_OK.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-335\" data-title=\"Slide\" data-thumb=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_04_OK-50x100.jpg\" data-anim=\"ms:1000;r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bca.ad\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"signatura_kappa_04_OK\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_04_OK.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-336\" data-title=\"Slide\" data-thumb=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_05_OK-50x100.jpg\" data-anim=\"ms:1000;r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/www.bca.ad\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" title=\"signatura_kappa_05_OK\" width=\"1920\" height=\"1080\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.bca.ad\/wp-content\/uploads\/2024\/06\/signatura_kappa_05_OK.jpg\" data-no-retina>\n<!---->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_16_1',rl:[1240,1024,778,480],el:[720,768,960,720],gw:[1280,1280,1280,1280],gh:[720,720,720,720],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider161\"]!==undefined) {window.RS_MODULES.modules[\"revslider161\"].once = false;window.revapi16 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El B\u00e0squet Club MoraBanc Andorra y Kappa han llegado a un acuerdo de alianza para que la marca deportiva sea el Patrocinador t\u00e9cnico oficial por las siguientes dos temporadas: 2024\/2025 y 2025\/2026. &nbsp; Mediante este acuerdo, Kappa vestir\u00e1 al equipo en todas sus competiciones y proporcionar\u00e1 material t\u00e9cnico necesario para los entrenamientos y partidos. Esta [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":35214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,1409,109,98],"tags":[],"class_list":["post-35215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-bcl-es","category-morabanc-andorra-es","category-noticia-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/35215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=35215"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/35215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/35214"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=35215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=35215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=35215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}