{"id":35472,"date":"2024-07-29T12:54:23","date_gmt":"2024-07-29T10:54:23","guid":{"rendered":"https:\/\/www.bca.ad\/el-morabanc-andorra-ya-conoce-el-calendario-de-una-nueva-temporada-en-la-liga-endesa\/"},"modified":"2024-07-31T13:58:46","modified_gmt":"2024-07-31T11:58:46","slug":"calendario-acb-2024-2025","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/calendario-acb-2024-2025\/","title":{"rendered":"El MoraBanc Andorra ya conoce el calendario de una nueva temporada en la Liga Endesa"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>La ACB ha hecho p\u00fablico, durante la ma\u00f1ana de hoy, los enfrentamientos con fechas y horas provisionales para este curso 2024\/2025.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La Liga Endesa arrancar\u00e1 por el MoraBanc Andorra el d\u00eda 28 de septiembre (20:45h) en la Bombonera. Para iniciar los desplazamientos, un primer plato fuerte: Baskonia. Los de Natxo Lezkano jugar\u00e1n en el Buesa Arena de Vitoria el s\u00e1bado 5 de octubre (18:00h). Tambi\u00e9n retos importantes en la Bombonera los que siguen, con la visita del reci\u00e9n ascendido Leyma Coru\u00f1a (s\u00e1bado 12 de octubre a las 20:45h) y del siempre complicado Coviran Granada (s\u00e1bado 26 de octubre a las 20:45h). El primer duelo ante el Bar\u00e7a ser\u00e1 en el Palau Blaugrana por fechas navide\u00f1as (domingo 22 de diciembre a las 17:00h), mientras que el vigente campe\u00f3n de liga, el Real Madrid, nos visitar\u00e1 en la Bombonera el domingo 19 de enero a las 18:30 horas. En la segunda vuelta, llegar\u00e1n los desplazamientos m\u00e1s largos: Dreamland Gran Canaria, R\u00edo Breog\u00e1n, La Laguna Tenerife, Unicaja, Leyma Basquet Coru\u00f1a y Coviran Granada. Por otro lado, en la Bombonera recibiremos las visitas de Valencia Basket (s\u00e1bado 1 de febrero a las 20:45h), Baskonia (domingo 2 de marzo a las 17:00h) y Bar\u00e7a (domingo 16 de marzo a las 17:00h). Cerraremos la liga regular visitando al Coviran Granada en una jornada 34 donde todav\u00eda no sabemos ni d\u00eda ni hora.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/ql.e-c.al\/2Eb7Qo1\" rel=\"noopener\" target=\"_blank\"><strong>Sincroniza el calendario a tu dispositivo m\u00f3vil.<\/strong><\/a><\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/www.bca.ad\/wp-content\/uploads\/2024\/07\/Calendario2425_Nou_ok.pdf\" rel=\"noopener\" target=\"_blank\"><strong>Desc\u00e1rgate aqu\u00ed todo el calendario.<\/strong><\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ACB ha hecho p\u00fablico, durante la ma\u00f1ana de hoy, los enfrentamientos con fechas y horas provisionales para este curso 2024\/2025. &nbsp; La Liga Endesa arrancar\u00e1 por el MoraBanc Andorra el d\u00eda 28 de septiembre (20:45h) en la Bombonera. Para iniciar los desplazamientos, un primer plato fuerte: Baskonia. Los de Natxo Lezkano jugar\u00e1n en el [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":35469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109,98],"tags":[1037,317,1177,205,1402],"class_list":["post-35472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es","category-noticia-es","tag-acb-es-2","tag-calendario","tag-lliga-endesa-es-2","tag-morabanc-andorra","tag-temporada-2024-2025-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/35472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=35472"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/35472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/35469"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=35472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=35472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=35472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}