{"id":37353,"date":"2025-08-11T15:07:03","date_gmt":"2025-08-11T13:07:03","guid":{"rendered":"https:\/\/www.bca.ad\/la-potencia-de-yves-pons-cierra-el-equipo\/"},"modified":"2025-08-11T16:05:14","modified_gmt":"2025-08-11T14:05:14","slug":"fichaje-yves-pons-25-26","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/fichaje-yves-pons-25-26\/","title":{"rendered":"La potencia de Yves Pons cierra el equipo"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Acuerdo cerrado entre el ala p\u00edvot franc\u00e9s Yves Pons y el BC MoraBanc Andorra para las pr\u00f3ximas dos temporadas.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Yves Pons (26 a\u00f1os y 197 cm) es nacido en Port-au-Prince, Hait\u00ed, y llega procedente del B\u00e0squet Girona, donde ha estado las \u00faltimas dos temporadas. Es un jugador que ha destacado por su perfil atl\u00e9tico y f\u00edsico, el cual le da ventaja en el rebote y en su capacidad de jugar por encima del aro. Tambi\u00e9n domina el juego sin bal\u00f3n y tiene un buen lanzamiento de tres puntos a pies parados.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El nuevo jugador del MoraBanc Andorra comenz\u00f3 su carrera con los Tenessee Volunteers de Knoxville, con quienes jug\u00f3 en la NCAA des del 2017 al 2021. M\u00e1s adelante, lleg\u00f3 a debutar en la NBA de la mano de los Memphis Grizzlies mientras participaba tambi\u00e9n en la G-League con los Memphis Hustle. Una vez dada por finalizada su experiencia en Estados Unidos, fich\u00f3 la temporada 2022\/2023 por el LDLC ASVEL, con quien compagin\u00f3 la liga francesa con la Euroliga. Despu\u00e9s de este curso en Francia ya aterriz\u00f3 en la Liga Endesa con los gerundenses. Pons tambi\u00e9n ha disputado partidos con la selecci\u00f3n absoluta francesa.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Francesc Solana<\/strong>, <strong>General Manager del BC MoraBanc Andorra<\/strong>, nos aporta su valoraci\u00f3n sobre la llegada de <strong>Yves Pons<\/strong> al conjunto tricolor: <strong>&#8220;Yves es un jugador con experiencia en la liga y que tiene un gran potencial, el cual ha demostrado en la NBA, Euroliga y tambi\u00e9n en Girona. Para nosotros ser\u00e1 un jugador muy importante gracias a su polivalencia, ya que puede cubrir diferentes posiciones. Con \u00e9l tendremos un perfil y un tono atl\u00e9tico que antes no ten\u00edamos, esperamos que tenga un gran rendimiento con nosotros&#8221;<\/strong>.<\/p>\n<p>&nbsp;<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/HtGSFNO5lWU?si=NuvHvYDbc7G-pmzA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acuerdo cerrado entre el ala p\u00edvot franc\u00e9s Yves Pons y el BC MoraBanc Andorra para las pr\u00f3ximas dos temporadas. &nbsp; Yves Pons (26 a\u00f1os y 197 cm) es nacido en Port-au-Prince, Hait\u00ed, y llega procedente del B\u00e0squet Girona, donde ha estado las \u00faltimas dos temporadas. Es un jugador que ha destacado por su perfil atl\u00e9tico [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":37351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[944,150,109,98],"tags":[1406,1632,1644],"class_list":["post-37353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acb-es","category-basquet-club-andorra-es","category-morabanc-andorra-es","category-noticia-es","tag-fichaje","tag-temporada-2025-2026-es","tag-yves-pons-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/37353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=37353"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/37353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/37351"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=37353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=37353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=37353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}