{"id":7984,"date":"2016-07-11T10:24:25","date_gmt":"2016-07-11T10:24:25","guid":{"rendered":"http:\/\/www.bca.ad\/beka-burjanadze-soc-un-jugador-amb-cor-grapa-i-caracter\/?lang=es"},"modified":"2016-07-11T10:27:37","modified_gmt":"2016-07-11T10:27:37","slug":"beka-burjanadze-soc-un-jugador-amb-cor-grapa-i-caracter","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/beka-burjanadze-soc-un-jugador-amb-cor-grapa-i-caracter\/","title":{"rendered":"Beka Burjanadze: &#8220;soy un jugador con coraz\u00f3n, garra y car\u00e1cter&#8221;"},"content":{"rendered":"<p><strong>Beka Burjanadze sabe que tiene delante la gran oportunidad con la que lleva a\u00f1os so\u00f1ando<\/strong>. Pero no s\u00f3lo so\u00f1ando, tambi\u00e9n trabajando duro. Desde que lleg\u00f3 a Espa\u00f1a para empezar a progresar con la cantera del Sevilla, el jugador georgiano ha esperado el momento de llegar a una plantilla ACB como un integrante m\u00e1s. Ya sabe lo que es jugar en la m\u00e1xima categor\u00eda pero fue en Sevilla justo cuando era una promesa. En la <strong>entrevista concedida a www.bca.ad<\/strong>, el ala-p\u00edvot muestra un <strong>generoso repertorio de determinaci\u00f3n, ilusi\u00f3n y entusiasmo<\/strong>, tres ingredientes que le pueden resultar muy provechosos al nuevo proyecto de Joan Pe\u00f1arroya.<\/p>\n<p><strong>-\u00bfQu\u00e9 Le llev\u00f3 a aceptar la oferta del MoraBanc Andorra?<\/strong><br \/>\n-Desde los 15 a\u00f1os que tengo un objetivo, desde que llegu\u00e9 a Espa\u00f1a y es jugar en la ACB. Esta temporada, gracias a Dios, creo que he ayudado bien mi equipo e individualmente pienso que tambi\u00e9n he estado bien. Por eso Andorra me ha dado esta opci\u00f3n y para m\u00ed es la mejor que pod\u00eda escoger. Ten\u00eda varias ofertas pero la de Andorra era la mejor. Tambi\u00e9n habl\u00e9 con Gio Shermadini con quien tengo mucha confianza y desde hace a\u00f1os. \u00c9l me habl\u00f3 sobre el equipo, la afici\u00f3n, el entrenador y la gente que trabaja en el club. Y con toda esta informaci\u00f3n decid\u00ed fichar por MoraBanc Andorra. Estoy muy ilusionado y con ganas de que llegue el momento de ponerme a trabajar.<br \/>\n<strong>-\u00bfQu\u00e9 objetivos se marca para la pr\u00f3xima temporada?<\/strong><\/p>\n<p>-Ayudar al equipo al m\u00e1ximo en todo lo que me pida el entrenador. Pero lo m\u00e1s importante es seguir mejorando como jugador. Soy un jugador joven y necesito mejorar en muchas cosas y Andorra es el lugar donde podr\u00e9 avanzar.<br \/>\n<strong>-Tenemos que entender que Shermadini ha sido decisivo para que usted fichara?<\/strong><\/p>\n<p>-Con o sin Shermadini yo creo que hubiera aceptado la oferta del MoraBanc Andorra. Yo he de escoger el mejor para m\u00ed y para mi familia. Pero la renovaci\u00f3n de Shermadini por una temporada m\u00e1s me ha ayudado mucho todo, como dec\u00eda, pidi\u00e9ndole los detalles sobre el club y la ciudad. Aparte de eso nos conocemos y siempre he so\u00f1ado jugar al lado de un georgiano en un clunb profesional. Sobre Shermadin qu\u00e9 puedo decir? Es un buen amigo, muy profesional. Y un t\u00edo muy gracioso (r\u00ede).<br \/>\n&#8211;<strong>Repasando su trayectoria parece que es un hombre que no para de mejorar.<\/strong><\/p>\n<p>-La \u00daltima temporada es la mejor que he tenido pero este es el fruto del trabajo que hice en Sevilla con 17 a\u00f1os y tambi\u00e9n por el trabajo que he hecho en Coru\u00f1a con entrenadores que me han ayudado mucho a mejorar. El trabajo para m\u00ed no ha terminado, tengo que seguir por este camino y tengo que hacer lo posible para seguir mejorando. Estoy contento por tener la oportunidad. Con este paso comienza todo.<br \/>\n<strong>-Usted es un jugador con garra. La segunda vuelta del MoraBanc Andorra la temporada pasada pareci\u00f3 que faltaba un poco de eso.<\/strong><\/p>\n<p>-Segu\u00ed todos los partidos de Gio Shermadini por lo tanto creo que vi casi todos los partidos del equipo aunque en ese momento no sab\u00eda que yo mismo acabar\u00eda fichando. A m\u00ed me encanta jugar con coraz\u00f3n, con garra. Con car\u00e1cter. Poner energ\u00eda en el equipo y transmitirla a mis compa\u00f1eros. Jugando o en el banquillo. Soy muy hablador en la pista, y no hablo de trash talking eh? (R\u00ede). Soy de animar a mis compa\u00f1eros y creo que eso sube el nivel de energ\u00eda y de motivaci\u00f3n. Me gusta jugar duro y as\u00ed llegaremos lejos y no nos faltar\u00e1 este impulso final de la temporada.<br \/>\n<strong>-Con Qu\u00e9 sue\u00f1a para su carrera?<\/strong><\/p>\n<p>-Yo De momento, me estoy imaginando en el primer partido que tendremos con MoraBanc Andorra. No te puedes imaginar c\u00f3mo estoy esperando este d\u00eda. Me gusta poner los objetivos a corto plazo y me ha ido muy bien hasta ahora en mi carrera y en mi vida personal. Tras hablar de objetivos como Copa del Rey o playoff es un objetivo colectivo y yo har\u00e9 todo lo posible para que se haga realidad.<br \/>\n<strong>-Y un debate que lo acompa\u00f1a siempre. Burjanadze es un 3 o un 4?<\/strong><\/p>\n<p>-Esta Pregunta siempre me la han hecho. Yo me veo jugando de 4. He hablado con el entrenador y me ha transmitido que \u00e9l cree que yo puedo ayudar al equipo jugando de 4. Si sigo trabajando individualmente creo que podr\u00e9 jugar de 3. Jugando de 4 puedo abrir el campo , cargar en el rebote ofensivo y defensivo y puedo hacer da\u00f1o.<br \/>\n<strong>-D\u00edgame Cu\u00e1l es su jugador favorito. En qui\u00e9n se fija?<\/strong><\/p>\n<p>-Mi Jugador favorito de todos los tiempos es Charles Barkley. Que era alto como yo m\u00e1s o menos pero que era una bestia. Tambi\u00e9n me gusta mucho Carmelo Anthony pero ahora mismo no tengo un jugador favorito al nivel de Barkley. Es mi \u00eddolo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beka Burjanadze sabe que tiene delante la gran oportunidad con la que lleva a\u00f1os so\u00f1ando. Pero no s\u00f3lo so\u00f1ando, tambi\u00e9n trabajando duro. Desde que lleg\u00f3 a Espa\u00f1a para empezar a progresar con la cantera del Sevilla, el jugador georgiano ha esperado el momento de llegar a una plantilla ACB como un integrante m\u00e1s. Ya sabe [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":7982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[152,325,611,243,521,347,163],"class_list":["post-7984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es","tag-acb-es","tag-acbandorra-es","tag-burjanadze-es","tag-liga-endesa-es","tag-morabanc-andorra-es2","tag-navarro-es","tag-penarroya-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/7984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=7984"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/7984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/7982"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=7984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=7984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=7984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}