{"id":8962,"date":"2016-12-07T12:43:57","date_gmt":"2016-12-07T12:43:57","guid":{"rendered":"http:\/\/www.bca.ad\/nou-acces-pels-espectadors-al-poliesportiu\/?lang=es"},"modified":"2016-12-07T16:55:10","modified_gmt":"2016-12-07T16:55:10","slug":"nou-acces-pels-espectadors-al-poliesportiu","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/nou-acces-pels-espectadors-al-poliesportiu\/","title":{"rendered":"Nuevo acceso para los aficionados a la BMB"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Calibri;\">&#8220;El objetivo es descongestionar el m\u00e1ximo posible los accesos al Polideportivo&#8221; expone el responsable de la organizaci\u00f3n de los partidos del MoraBanc Andorra Sergi Romero. &#8220;El nuevo acceso conducir\u00e1 a muchos espectadores de manera diferente a la instalaci\u00f3n y contribuir\u00e1 seguro a que ning\u00fan aficionado entre tarde a los partidos para hacer cola, algo que se hab\u00eda dado en alguna ocasi\u00f3n&#8221; argumenta el gerente del club.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\nLos espectadores que se sienten en el lateral inferior o en el fondo Pidasa podr\u00e1n acceder a la BMB a trav\u00e9s de la puerta situada al lado de la conserjer\u00eda del pabell\u00f3n (como si fueran a buscar el trayecto que lleva al Joan Alay. En all\u00ed estar\u00e1 habilitada la nueva puerta.<\/span><\/p>\n<p>&#8220;El nuevo acceso tambi\u00e9n est\u00e1 marcado como el preferencial para todos los jugadores de nuestra base&#8221; ha completado Romero. El debut de la nueva herramienta ser\u00e1 toda una prueba de fuego, el partido de este domingo a las 18h contra el Fc Barcelona Lassa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;El objetivo es descongestionar el m\u00e1ximo posible los accesos al Polideportivo&#8221; expone el responsable de la organizaci\u00f3n de los partidos del MoraBanc Andorra Sergi Romero. &#8220;El nuevo acceso conducir\u00e1 a muchos espectadores de manera diferente a la instalaci\u00f3n y contribuir\u00e1 seguro a que ning\u00fan aficionado entre tarde a los partidos para hacer cola, algo que [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[152,325,606,347,163,326,510,624],"class_list":["post-8962","post","type-post","status-publish","format-standard","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es","tag-acb-es","tag-acbandorra-es","tag-albicy-es","tag-navarro-es","tag-penarroya-es","tag-sada-es","tag-shermadini-es","tag-walker-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/8962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=8962"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/8962\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=8962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=8962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=8962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}