{"id":9461,"date":"2017-02-15T20:18:24","date_gmt":"2017-02-15T20:18:24","guid":{"rendered":"http:\/\/www.bca.ad\/previa-no-es-un-somni-es-la-copa\/?lang=es"},"modified":"2017-02-15T20:24:20","modified_gmt":"2017-02-15T20:24:20","slug":"previa-no-es-un-somni-es-la-copa","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/previa-no-es-un-somni-es-la-copa\/","title":{"rendered":"(PREVIA) No es un sue\u00f1o, es la Copa"},"content":{"rendered":"<p><span style=\"font-family: Calibri;\"><span style=\"color: #000000;\"><strong>Ma\u00f1ana a las 21h30 (Tv en # 0 Movistar + y radio\u00a0en RNA y SER Andorra) el Bc MoraBanc Andorra vivir\u00e1 un d\u00eda hist\u00f3rico<\/strong>. <span title=\"S\u2019enfrontar\u00e0 en els quarts de final de la Copa, el Reial Madrid, el club m\u00e9s llorejat del b\u00e0squet mundial.\">Se enfrentar\u00e1 en los cuartos de final de la Copa, el<strong> Real Madrid, el club m\u00e1s laureado<\/strong> del baloncesto mundial. <\/span><\/span><strong><span title=\"Sobre el paper, l\u2019excitaci\u00f3 per la situaci\u00f3 \u00e9s m\u00e1xima.\"><span style=\"color: #000000;\">Sobre el papel, la excitaci\u00f3n por la situaci\u00f3n es m\u00e1xima. <\/span><\/span><\/strong><span style=\"color: #000000;\"><span title=\"200 persones vingudes des d\u2019Andorra animaran l\u2019equip de Joan Pe\u00f1arroya en una d\u2019aquelles cites que quedaran per sempre en la mem\u00f2ria dels bons aficionats al b\u00e0squet i tamb\u00e9 a l\u2019esport del pa\u00eds.\"><strong>200 personas venidas desde Andorra animar\u00e1n el equipo de Joan Pe\u00f1arroya en una de esas citas que quedar\u00e1n para siempre en la memoria de los buenos aficionados al baloncesto y tambi\u00e9n\u00a0al deporte del pa\u00eds<\/strong>. <\/span><span title=\"Per\u00f2 clar, un dia d\u2019un perfil tant alt, tamb\u00e9 comporta competir i m\u00e9s en un torneig curt i ben equipat per acollir sorpreses com la Copa del Rei.\">Pero claro, un d\u00eda de un perfil tan alto, tambi\u00e9n conlleva competir y m\u00e1s en un torneo corto y bien equipado para acoger sorpresas como la Copa del Rey. <\/span><span title=\"Per tant un dels primers reptes de Pe\u00f1arroya i els seus ajudants ser\u00e0 aiilar l'equip de tot el que envolta el partit, que s\u00f3n molts factors llaminers abonats a la distracci\u00f3 i centrar l'esfor\u00e7 en la monumental tasca de derrotar el Reial Madrid, el\">Por lo tanto uno de los primeros retos de Pe\u00f1arroya y sus ayudantes ser\u00e1 aislar el equipo de todo lo que rodea al partido, ya que son muchos los factores golosos abonados a la distracci\u00f3n y centrar el esfuerzo en la monumental tarea de derrotar al Real Madrid, el <\/span><span title=\"campi\u00f3 de les tres darreres edicions d'aquesta competici\u00f3 i el millor equip d'Espanya a dia d'avui segons tots els experts.\">campe\u00f3n de las tres \u00faltimas ediciones de esta competici\u00f3n y el mejor equipo de Espa\u00f1a a d\u00eda de hoy seg\u00fan todos los expertos. <\/span><span title=\"La baixa de Nacho Mart\u00edn complica les coses per\u00f2 l\u2019equip ha arribat a acostumar-se les darreres setmanes a viure sense una pe\u00e7a tant important.\">La baja de Nacho Mart\u00edn complica las cosas pero el equipo ha llegado a acostumbrarse las \u00faltimas semanas a vivir sin una pieza tan importante. <\/span><span title=\"L\u2019aler pivot madrileny, per cert, s\u2019ha despla\u00e7at amb els seus companys en bus, amb crosses, per animar-los.\">El ala-p\u00edvot madrile\u00f1o, por cierto, se ha desplazado con sus compa\u00f1eros en bus, con muletas, para animarles. <\/span><\/span><\/span><span style=\"font-family: Calibri;\"><span title=\"Un exemple m\u00e9s de la gran qu\u00edmica que t\u00e9 aquest equip. \"><span style=\"color: #000000;\">Un ejemplo m\u00e1s de la gran qu\u00edmica que tiene este equipo. <strong>Ante los tricolores ma\u00f1ana, el Madrid con todo el arsenal. Llull, Doncic, Reyes, Ay\u00f3n, Carroll y compa\u00f1\u00eda. Una constelaci\u00f3n de estrellas, pero que en el \u00faltimo precedente s\u00f3lo pudo derrotar a\u00a0los de Pe\u00f1arroya en la pr\u00f3rroga.<\/strong><br \/>\n<\/span> <\/span><span style=\"color: #000000;\"><span title=\"\u201cPodem tenir les nostres opcions per\u00f2 haurem de fer les coses b\u00e9 i commettre pocs errors no for\u00e7ats.\"><strong>&#8220;Podemos tener nuestras opciones pero tendremos que hacer las cosas bien y commettre pocos errores no forzados<\/strong>. <\/span><span title=\"Hem de ser conscients sempre del partit que ens conv\u00e8 i no perdre mai la concentraci\u00f3 perqu\u00e8 ells ens poden fer molt de mal\u201c afirma el capit\u00e0 David Navarro, que ha estat objecte de moltes entrevistes en l'arribada de l'equip a l'hotel\">Debemos ser conscientes siempre del partido que nos conviene y no perder nunca la concentraci\u00f3n para que ellos nos pueden hacer mucho da\u00f1o &#8220;<strong>afirma el capit\u00e1n David Navarro,<\/strong> que ha sido objeto de muchas entrevistas en la llegada del equipo en el hotel <\/span><span title=\"on estan allotjats tots els equips participants.\">donde est\u00e1n alojados todos los equipos participantes. <\/span><\/span><\/span><span style=\"font-family: Calibri;\"><span title=\"Una aut\u00e8ntica olla a pressi\u00f3 que cuina b\u00e0squet sense parar amb molts mitjans de comunicaci\u00f3 esperant l\u2019arribada dels equips participants. \"><span style=\"color: #000000;\">Una aut\u00e9ntica olla a presi\u00f3n que cocina baloncesto sin parar con muchos medios de comunicaci\u00f3n esperando la llegada de los equipos participantes.<br \/>\n<\/span> <\/span><span style=\"color: #000000;\"><span title=\"\u201cJugarem un partit obert, valent, no sabem fer-ho d\u2019una altra manera\u201d ha manifestat Joan Pe\u00f1arroya aquest mat\u00ed quan ha at\u00e8s la premsa abans de pujar-se al bus cam\u00ed de Vit\u00f2ria.\"><strong>&#8220;Jugaremos un partido abierto, valiente, no sabemos hacerlo de otra manera&#8221; ha manifestado Joan Pe\u00f1arroya<\/strong> esta ma\u00f1ana cuando ha atendido a la prensa antes de subirse al bus camino de Vitoria. <\/span><span title=\"\u201cSabem que juguem contra el gran favorit per guanyar la competici\u00f3 per\u00f2 podem tenir les nostres opcions si ataquem i defensem molt b\u00e9, tot passa per fer un partit perfecte\u201d afirma el t\u00e8cnic, que com a jugador va aixecar la Copa del Rei els anys 90\">&#8220;Sabemos que jugamos contra el gran favorito para ganar la competici\u00f3n pero podemos tener nuestras opciones si atacamos y defendemos muy bien, todo pasa por hacer un partido perfecto&#8221; afirma el t\u00e9cnico, que como jugador levant\u00f3 la Copa del Rey los a\u00f1os 90 <\/span><span title=\"jugant amb el TDK Manresa.\">jugando con el TDK Manresa. <\/span><span title=\"Sobre la capacitat de la Copa per generar sorpreses Pe\u00f1arroya s\u2019ha mostrat prudent \u201c\u00e9s evident que se\u2019n poden donar per\u00f2 hem de fer les coses molt b\u00e9.\">Sobre la capacidad de la Copa para generar sorpresas Pe\u00f1arroya ha mostrado prudente &#8220;es evidente que se pueden dar pero tenemos que hacer las cosas muy bien. <\/span><\/span><\/span><span style=\"font-family: Calibri;\"><span title=\"A vegades t\u2019emoortes alegries que recordes sempre com aquella Copa amb el TDK\u201d. \"><span style=\"color: #000000;\">A veces te llevas alegr\u00edas que recuerdas siempre como aquella Copa con el TDK &#8220;.<br \/>\n<\/span> <\/span><span title=\"El t\u00e8cnic del MoraBanc Andorra ha volgut enviar un missatge als seguidors andorrans, als que vindran a Vit\u00f2ria i als que ho seguir\u00e1n per televisi\u00f3, r\u00e0dio o xarxes \u201cque gaudeixin i molt d'aquest gran esdeveniment perqu\u00e8 no fa massa anys era impensable que poguessim estar\"><span style=\"color: #000000;\"><strong>El t\u00e9cnico del MoraBanc Andorra ha querido enviar un mensaje a los seguidores andorranos, a los que vendr\u00e1n a Vitoria y los que lo seguir\u00e1n por televisi\u00f3n, radio o redes &#8220;que disfruten y mucho de este gran evento porque no hace muchos a\u00f1os era impensable<\/strong> que pudi\u00e9ramos estar <\/span><\/span><\/span><span style=\"font-family: Calibri;\"><span title=\"aqu\u00ed i hi som\u201d. \"><span style=\"color: #000000;\">aqu\u00ed y estamos &#8220;.<br \/>\n<\/span> <\/span><span style=\"color: #000000;\"><span title=\"El MoraBanc Andorra, quan era Festina Andorra, va disputar una fase final de la Copa del Rei.\">El MoraBanc Andorra, cuando era Festina Andorra, disput\u00f3 una fase final de la Copa del Rey. <\/span><span title=\"Va ser fa 22 anys i en aquella ocasi\u00f3 l\u2019Estudiantes va ser el botx\u00ed dels tricolors amb un triple al darrer segon.\">Fue hace 22 a\u00f1os y en aquella ocasi\u00f3n el Estudiantes fue el verdugo de los tricolores con un triple en el \u00faltimo segundo. <\/span><span title=\"Dues d\u00e8cades despr\u00e8s, Herreros \u00e9s el director esportiu del Reial Madrid.\">Dos d\u00e9cadas despu\u00e9s, Herreros es el director deportivo del Real Madrid. <\/span><\/span><\/span><span style=\"font-family: Calibri;\"><span title=\"L\u2019esport sempre dona opci\u00f3 de vendetta, encara que el paper avui del MoraBanc davant dels blancs \u00e9s molt de v\u00edctima propiciat\u00f2ria que el que es va donar en el duel de fa 22 anys a Granada. \"><span style=\"color: #000000;\">El deporte siempre da opci\u00f3n de vendetta, aunque el papel hoy del MoraBanc ante los blancos es mucho v\u00edctima propiciatoria que lo que se dio en el duelo de hace 22 a\u00f1os en Granada.<br \/>\n<\/span> <\/span><span style=\"color: #000000;\"><span title=\"La Copa arrenca dem\u00e0 a les 18h30 amb el matx entre el Baskonia i l\u2019Herbalife Gran Can\u00e0ria.\"><strong>La Copa arranca ma\u00f1ana a las 18h30 con el encuentro entre el Baskonia y el Iberostar Tenerife<\/strong>. <\/span><span title=\"A continuaci\u00f3 el MoraBanc Andorra-Reial Madrid que pot paralitzar el pa\u00eds davant del televisor.\">A continuaci\u00f3n el MoraBanc Andorra-Real Madrid que puede paralizar el pa\u00eds frente al televisor. <\/span><span title=\"Al World Champions by 99 de Jorge Lorenzo, al costat de Pyr\u00e9n\u00e9es conviden a tots els abonats a una cerveza si van a veure el partit.\">En el World Champions by 99 de Jorge Lorenzo, junto a Pyr\u00e9n\u00e9es invitan a todos los abonados a una cerveza si van a ver el partido. <\/span><span title=\"L\u2019Art Hotel fa un 10% de descompte a qui vagi a sopar durant el partit.\">El Art Hotel hace un 10% de descuento a quien vaya a cenar durante el partido. <\/span><span title=\"El Don Denis tamb\u00e9 t\u00e9 un 10% de descompte pels abonats que mostrin el seu carnet.\">El Don Denis tambi\u00e9n tiene un 10% de descuento para los abonados que muestren su carn\u00e9.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana a las 21h30 (Tv en # 0 Movistar + y radio\u00a0en RNA y SER Andorra) el Bc MoraBanc Andorra vivir\u00e1 un d\u00eda hist\u00f3rico. Se enfrentar\u00e1 en los cuartos de final de la Copa, el Real Madrid, el club m\u00e1s laureado del baloncesto mundial. Sobre el papel, la excitaci\u00f3n por la situaci\u00f3n es m\u00e1xima. 200 [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":9459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[152,606,239,153,521,347,163,384,510,246,624],"class_list":["post-9461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es","tag-acb-es","tag-albicy-es","tag-francesc-solana-ca-es","tag-lliga-endesa-es","tag-morabanc-andorra-es2","tag-navarro-es","tag-penarroya-es","tag-schreiner-es","tag-shermadini-es","tag-thomas-schreiner-es","tag-walker-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/9461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=9461"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/9461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/9459"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=9461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=9461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=9461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}