{"id":9724,"date":"2017-03-28T09:48:21","date_gmt":"2017-03-28T09:48:21","guid":{"rendered":"http:\/\/www.bca.ad\/shermadini-mvp-acb-del-mes-de-marc\/?lang=es"},"modified":"2017-03-28T09:50:28","modified_gmt":"2017-03-28T09:50:28","slug":"shermadini-mvp-acb-del-mes-de-marc","status":"publish","type":"post","link":"https:\/\/www.bca.ad\/es\/shermadini-mvp-acb-del-mes-de-marc\/","title":{"rendered":"Shermadini MVP ACB del mes de marzo"},"content":{"rendered":"<p><span style=\"color: #000000; font-family: Calibri;\"><strong>Giorgi Shermadini ha cerrado el mes de marzo con una incre\u00edble valoraci\u00f3n media de 25,75 puntos, cifra que le otorga la designaci\u00f3n como MVP Movistar por parte de la Liga Endesa<\/strong>. <\/span><span title=\"Per al gegant georgi\u00e0 \u00e9s la segona designaci\u00f3 de la temporada i de la seva carrera a la competici\u00f3.\n\n\"><span style=\"color: #000000; font-family: Calibri;\">Para el gigante georgiano es la segunda designaci\u00f3n de la temporada y de su carrera en la competici\u00f3n.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><span title=\"Gio ha estat el gran dominador del mar\u00e7 amb uns n\u00fameros que han perm\u00e8s al MoraBabc Andorra mantenir-se en llocs de Playoff, amb un balan\u00e7 de dues vict\u00f2ries i dues derrotes en les quatre jornades disputades.\n\n\"><span style=\"color: #000000; font-family: Calibri;\"><strong>Gio ha sido el gran dominador del marzo con unos n\u00fameros que han permitido al MoraBabc Andorra mantenerse en puestos de Playoff<\/strong>, con un balance de dos victorias y dos derrotas en las cuatro jornadas disputadas.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span title=\"La seva millor actuaci\u00f3 del mar\u00e7 va arribar a la Bombonera contra el Tecnyconta Saragossa.\">Su mejor actuaci\u00f3n de marzo lleg\u00f3 a la Bombonera contra el Tecnyconta Zaragoza. <\/span><span title=\"En aquest partit, Shermadini va estar espectacular, aconseguint 27 punts, 9 rebots, 10 faltes rebudes i 41 de valoraci\u00f3.\">En este partido, Shermadini estuvo espectacular, consiguiendo 27 puntos, 9 rebotes, 10 faltas recibidas y 41 de valoraci\u00f3n. <\/span><span title=\"Va ser MVP de la jornada.\">Fue MVP de la jornada. <\/span><span title=\"El pivot del MoraBanc Andorra ha tancat el mar\u00e7 amb una valoraci\u00f3 mitjana de 25,75 punts per partit, sent la resta de les seves mitjanes al mes de mar\u00e7 de 19,25 punts anotats, 6,5 rebots capturats, 0,5 assist\u00e8ncies repartides\">El p\u00edvot del MoraBanc Andorra ha cerrado marzo con una valoraci\u00f3n media de 25,75 puntos por partido, siendo el resto de sus medias en el mes de marzo de 19,25 puntos anotados, 6,5 rebotes capturados, 0,5 asistencias repartidas <\/span><\/span><\/span><span title=\", 1,25 pilotes recuperades, 0,5 taps col\u00b7locats i 7,0 faltes rebudes.\n\n\"><span style=\"color: #000000; font-family: Calibri;\">, 1,25 balones recuperados, 0,5 tapones colocados y 7,0 faltas recibidas.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><span title=\"Aix\u00ed, Giorgi Shermadini es mant\u00e9 com a m\u00e0xim rebotejador de la Lliga Endesa, amb 7,58 captures de mitjana per partit, a m\u00e9s de ser el segon jugador m\u00e9s valorat de la competici\u00f3 (22,0) i el tercer m\u00e0xim anotador (15,\"><span style=\"color: #000000; font-family: Calibri;\">As\u00ed, Giorgi Shermadini se mantiene como m\u00e1ximo reboteador de la Liga Endesa, con 7,58 capturas de media por partido, adem\u00e1s de ser el segundo jugador m\u00e1s valorado de la competici\u00f3n (22,0) y el tercer m\u00e1ximo anotador (15, <\/span><\/span><span title=\"5) .\n\n\"><span style=\"color: #000000; font-family: Calibri;\">5).<br \/>\n<\/span><strong><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/strong><\/span><span title=\"&quot;Em va sorprendre saber que s\u00f3c l'MVP&quot;\n\n\"><span style=\"color: #000000; font-family: Calibri;\"><strong>&#8220;Me sorprendi\u00f3 saber que soy el MVP&#8221;<\/strong><br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span title=\"Despr\u00e9s de con\u00e8ixer la seva designaci\u00f3, Giorgi Shermadini reconeixia ahir que &quot;em va sorprendre saber que s\u00f3c l'MVP Movistar de mar\u00e7, per\u00f2 s\u00f3n molt bones not\u00edcies&quot;.\">Tras conocer su designaci\u00f3n, Giorgi Shermadini reconoc\u00eda ayer que &#8220;me sorprendi\u00f3 saber que soy el MVP Movistar de marzo, pero son muy buenas noticias&#8221;. <\/span><span title=\"El pivot del MoraBanc Andorra va explicar que el seu equip va fer un mal partit a Barcelona en l'\u00faltima jornada, per\u00f2 ha assegurat que &quot;hem d'oblidar aquesta actuaci\u00f3 el m\u00e9s aviat que puguem i centrar-nos en el futur, en aprofitar\">El p\u00edvot del MoraBanc Andorra explic\u00f3 que su equipo hizo un mal partido en Barcelona en la \u00faltima jornada, pero asegur\u00f3 que &#8220;debemos olvidar esta actuaci\u00f3n lo antes que podamos y centrarnos en el futuro, al aprovechar <\/span><\/span><\/span><span title=\"les oportunitats per als nostres objectius&quot;.\n\n\"><span style=\"color: #000000; font-family: Calibri;\">las oportunidades para nuestros objetivos &#8220;.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><strong><span title=\"El georgi\u00e0 va recon\u00e8ixer que &quot;estic en un bon moment, per\u00f2 tots aquests reconeixements individuals tamb\u00e9 s\u00f3n per als meus companys&quot;.\"><span style=\"color: #000000; font-family: Calibri;\">El georgiano reconoci\u00f3 que &#8220;estoy en un buen momento, pero todos estos reconocimientos individuales tambi\u00e9n son para mis compa\u00f1eros&#8221;. <\/span><\/span><span title=\"Shermadini va destacar el paper de la resta d'integrants del MoraBanc Andorra i va explicar que &quot;sempre m'ajuden i si no fos per ells i per Joan Pe\u00f1arroya, no aconseguiria aquests guardons&quot;.\n\n\"><span style=\"color: #000000; font-family: Calibri;\">Shermadini destac\u00f3 el papel del resto de integrantes del MoraBanc Andorra y explic\u00f3 que &#8220;siempre me ayudan y si no fuera por ellos y por Joan Pe\u00f1arroya, no conseguir\u00eda estos galardones&#8221;.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span title=\"Pel que fa al futur de l'equip, l'interior georgi\u00e0 va afirmar que &quot;estem fent un gran treball, una bona temporada, i esperem poder acabar b\u00e9 el curs&quot;.\">En cuanto al futuro del equipo, el interior georgiano afirm\u00f3 que &#8220;estamos haciendo un gran trabajo, una buena temporada, y esperamos poder terminar bien el curso&#8221;. <\/span><span title=\"Shermadini va destacar la import\u00e0ncia de la propera trobada, davant del Movistar Estudiants, i va assegurar que &quot;tots dos necessitem la vict\u00f2ria, aix\u00ed que vindran a per totes. Ens hem de preparar, esperem poder parar a Edwin Jackson i la resta de jugadors,\">Shermadini destac\u00f3 la importancia del pr\u00f3ximo encuentro, ante el Movistar Estudiantes, y asegur\u00f3 que &#8220;ambos necesitamos la victoria, as\u00ed que vendr\u00e1n a por todas. Hay que prepararse, esperamos poder parar a Edwin Jackson y el resto de jugadores, <\/span><\/span><\/span><span title=\"perqu\u00e8 s\u00f3n bons jugadors &quot;.\n\n\"><span style=\"color: #000000; font-family: Calibri;\">porque son buenos jugadores &#8220;.<br \/>\n<\/span><span style=\"color: #000000; font-family: Calibri;\"><br \/>\n<\/span><\/span><strong><span title=\"Per finalitzar, el georgi\u00e0 va agrair l'incondicional suport de l'afici\u00f3 del MoraBanc Andorra i ha destacat que &quot;sempre estan amb nosaltres. S\u00e9 que s\u00f3n conscients de la import\u00e0ncia del partit contra el Movistar Estudiants i no ens fallaran &quot;.\"><span style=\"color: #000000; font-family: Calibri;\">Para finalizar, el georgiano agradeci\u00f3 el incondicional apoyo de la afici\u00f3n del MoraBanc Andorra y ha destacado que &#8220;siempre est\u00e1n con nosotros. S\u00e9 que son conscientes de la importancia del partido contra el Movistar Estudiantes y no nos fallar\u00e1n&#8221;.<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Giorgi Shermadini ha cerrado el mes de marzo con una incre\u00edble valoraci\u00f3n media de 25,75 puntos, cifra que le otorga la designaci\u00f3n como MVP Movistar por parte de la Liga Endesa. Para el gigante georgiano es la segunda designaci\u00f3n de la temporada y de su carrera en la competici\u00f3n. Gio ha sido el gran dominador [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":9722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[150,109],"tags":[152,325,177,243,521,347,163,384,510,246,624],"class_list":["post-9724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-club-andorra-es","category-morabanc-andorra-es","tag-acb-es","tag-acbandorra-es","tag-joan-penarroya-es","tag-liga-endesa-es","tag-morabanc-andorra-es2","tag-navarro-es","tag-penarroya-es","tag-schreiner-es","tag-shermadini-es","tag-thomas-schreiner-es","tag-walker-es"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/9724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/comments?post=9724"}],"version-history":[{"count":0,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/posts\/9724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media\/9722"}],"wp:attachment":[{"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/media?parent=9724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/categories?post=9724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bca.ad\/es\/wp-json\/wp\/v2\/tags?post=9724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}